{"id":354360,"date":"2021-02-11T11:04:37","date_gmt":"2021-02-11T17:04:37","guid":{"rendered":"http:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=354360"},"modified":"2021-02-11T11:04:38","modified_gmt":"2021-02-11T17:04:38","slug":"riesgo-sanitario-ante-irresponsabilidad-ciudadana","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/02\/11\/riesgo-sanitario-ante-irresponsabilidad-ciudadana\/","title":{"rendered":"Riesgo sanitario ante irresponsabilidad ciudadana"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"float:left\"><div class=\"counts mashsbcount\">0<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F02%2F11%2Friesgo-sanitario-ante-irresponsabilidad-ciudadana%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/02\/11\/riesgo-sanitario-ante-irresponsabilidad-ciudadana\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<ul class=\"wp-block-list\"><li><em>A pesar de las recomendaciones y supervisi\u00f3n de las autoridades municipales y de salud, un amplio n\u00famero de personas se niega a usar cubrebocas bajo argumento de es \u201cinc\u00f3modo\u201d.<\/em><\/li><\/ul>\n\n\n\n<p><strong>Xochiatipan, Hgo.-\u00a0<\/strong> No obstante que ayer se instalaron varios filtros en el tianguis local, donde se exigi\u00f3 a la gente portar el cubrebocas y aplicarse gel antibacterial como requisito indispensable para ingresar, en el interior decenas de personas fueron vistas sin usar dicha prenda.<\/p>\n\n\n\n<p>Desde temprana hora personal administrativo del gobierno local en turno, con el apoyo de elementos de seguridad p\u00fablica y por instrucciones del alcalde Oscar Bautista Guti\u00e9rrez, se instalaron en varias calles alrededor de la zona comercial para vigilar que los mercaderes y clientes portaran correcta y obligatoriamente el cubrebocas.<\/p>\n\n\n\n<p>De igual manera, personal de la Secretar\u00eda de Salud de Hidalgo adscrito a la Jurisdicci\u00f3n Sanitaria X, hizo acto de presencia para recorrer el tianguis y conminar a todos los presentes a asumir con responsabilidad medidas como uso de gel antibacterial y del cubrebocas.<\/p>\n\n\n\n<p>No obstante estas acciones preventivas, despu\u00e9s del medio d\u00eda clientes y comerciantes poco a poco se despojaron del cubrebocas, convirtiendo el d\u00eda de plaza en un enorme foco de riesgo de contagios no s\u00f3lo de COVID-19, sino de cualquier otra enfermedad respiratoria.<\/p>\n\n\n\n<p>Al realizar un sondeo entre la gente para conocer por qu\u00e9 se reh\u00fasan el cubrebocas, el argumento fue que resulta una pieza inc\u00f3moda, ya que \u2013 dicen &#8211; \u201cimpide poder hablar fuerte y claro, pero sobre todo, sofoca\u201d.<\/p>\n\n\n\n<p>Misma situaci\u00f3n pudo apreciarse en el transporte p\u00fablico de pasajeros, donde incluso los operadores de las unidades y los viajeros se dirigen a sus destinos ignorando la instrucci\u00f3n de abordar y tener bien colocado el cubrebocas.<\/p>\n\n\n\n<p>Cabe mencionar que desde semanas anteriores se ha visto la labor de la administraci\u00f3n municipal para mantener, de alguna manera, un control sobre la poblaci\u00f3n en cuanto al uso del cubrebocas, sin embargo, es la propia gente la que rechaza tal medida con excusas.<\/p>\n\n\n\n<p>Por otro lado, al cuestionar a varios comerciantes sobre sus motivos\u00a0 para no acatar las disposiciones sanitarias emitidas por las autoridades federales, estatales y municipales, responden que \u201cen las noticias no se ha dicho que en Xochiatipan haya casos de coronavirus, por lo que no hay necesidad de alarmarse\u201d.<\/p>\n\n\n\n<p><em>Por Le\u00f3n Eduardo Fern\u00e1ndez Huesca<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pesar de las recomendaciones y supervisi\u00f3n de las autoridades municipales y de salud, un amplio n\u00famero de personas se niega a usar cubrebocas bajo argumento de es \u201cinc\u00f3modo\u201d. Xochiatipan, Hgo.-\u00a0 No obstante que ayer se instalaron varios filtros en el tianguis local, donde se exigi\u00f3 a la gente portar el cubrebocas y aplicarse gel&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/02\/11\/riesgo-sanitario-ante-irresponsabilidad-ciudadana\/\">Seguir leyendo <span class=\"screen-reader-text\">Riesgo sanitario ante irresponsabilidad ciudadana<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":354301,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[179,202],"tags":[135],"class_list":["post-354360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huasteca","category-xochiatipan","tag-xochiatipan","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/354360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=354360"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/354360\/revisions"}],"predecessor-version":[{"id":354383,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/354360\/revisions\/354383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/354301"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=354360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=354360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=354360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}