{"id":390994,"date":"2021-08-26T21:00:39","date_gmt":"2021-08-27T02:00:39","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=390994"},"modified":"2021-08-26T21:00:40","modified_gmt":"2021-08-27T02:00:40","slug":"piden-a-poblacion-no-bajar-la-guardia-contra-el-dengue","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/26\/piden-a-poblacion-no-bajar-la-guardia-contra-el-dengue\/","title":{"rendered":"Piden a poblaci\u00f3n no bajar la guardia contra el dengue"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">181<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F08%2F26%2Fpiden-a-poblacion-no-bajar-la-guardia-contra-el-dengue%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/26\/piden-a-poblacion-no-bajar-la-guardia-contra-el-dengue\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por \u00c1ngel Silverio\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>San Felipe Orizatl\u00e1n, Hgo. &#8211;<\/strong> En el marco del D\u00eda Internacional contra el Dengue, las autoridades municipales han intensificado sus acciones para prevenir casos de esta enfermedad, por lo que contin\u00faan exhortando a la ciudadan\u00eda a que contin\u00faen realizando las acciones del programa denominado \u201cPatio Limpio\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a lo informado por la autoridad municipal que encabeza la alcaldesa Erika Saab Lara, mencionaron que es una fecha en la que se busca reiterar la importancia de mantener espacios libres de mosquitos para evitar una enfermedad como el Dengue, Zika o Chikungunya, por ello la recomendaci\u00f3n en casa es retirar cacharros u otros objetos que est\u00e9n en desuso para evitar que concentren agua y concentren criadero de mosquitos, sobretodo en esta temporada de lluvias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mencionan que es responsabilidad de todos, de los tres \u00f3rdenes de gobierno, estatal, federal y municipal, pero tambi\u00e9n la sociedad tiene que participar y para evitar que los casos se incrementen, las autoridades pidieron a la poblaci\u00f3n mantener limpios el patio y techo de sus viviendas y evitar la acumulaci\u00f3n de agua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe se\u00f1alar que se han estado realizando jornadas de descacharrizacion en los diferentes puntos de la cabecera municipal, as\u00ed como en las delegaciones municipales, donde tambi\u00e9n han solicitado que se lleve a cabo la fumigaci\u00f3n para evitar as\u00ed que se presenten casos de esta enfermedad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por \u00c1ngel Silverio\/Zunoticia San Felipe Orizatl\u00e1n, Hgo. &#8211; En el marco del D\u00eda Internacional contra el Dengue, las autoridades municipales han intensificado sus acciones para prevenir casos de esta enfermedad, por lo que contin\u00faan exhortando a la ciudadan\u00eda a que contin\u00faen realizando las acciones del programa denominado \u201cPatio Limpio\u201d. De acuerdo a lo informado por&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/26\/piden-a-poblacion-no-bajar-la-guardia-contra-el-dengue\/\">Seguir leyendo <span class=\"screen-reader-text\">Piden a poblaci\u00f3n no bajar la guardia contra el dengue<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":390995,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[180],"tags":[230],"class_list":["post-390994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orizatlan","tag-orizatlan-2","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/390994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=390994"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/390994\/revisions"}],"predecessor-version":[{"id":390996,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/390994\/revisions\/390996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/390995"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=390994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=390994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=390994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}