{"id":391034,"date":"2021-08-26T22:53:20","date_gmt":"2021-08-27T03:53:20","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=391034"},"modified":"2021-08-26T22:53:22","modified_gmt":"2021-08-27T03:53:22","slug":"detienen-a-cinco-de-banda-delictiva","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/26\/detienen-a-cinco-de-banda-delictiva\/","title":{"rendered":"Detienen a cinco de banda delictiva"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">325<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F08%2F26%2Fdetienen-a-cinco-de-banda-delictiva%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/26\/detienen-a-cinco-de-banda-delictiva\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo. &#8211;<\/strong> Cuatro personas del sexo masculino y una mujer fueron asegurados por elementos de la polic\u00eda municipal tras haber perpetrado un asalto a un conocido negocio de comida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los hechos ocurrieron presuntamente desde el pasado jueves en la cabecera municipal del municipio de Calnali, Hidalgo, cuando fue reportado a los elementos de la polic\u00eda municipal el atraco de un negocio por parte de varias personas, por lo que de inmediato acudieron hasta el lugar para apoyar a las v\u00edctimas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, al arribar hasta la zona los delincuentes hab\u00edan logrado huir llev\u00e1ndose en su poder dinero en efectivo y celulares, por lo que realizaron un operativo en el sitio para dar con el paradero de los responsables del robo, quienes minutos despu\u00e9s fueron asegurados por las autoridades polic\u00edacas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, los presuntos ladrones fueron identificados como L.M.G., P.H.E., I.H.R., P.C. y M.H.L. la cual se presume pertenecen a una banda dedicada al robo y extorsi\u00f3n, por lo que m\u00e1s tarde fueron puestos a disposici\u00f3n del ministerio p\u00fablico de Molango donde se llevar\u00e1 su situaci\u00f3n legal al ser denunciados por la parte afectada, cabe hacer menci\u00f3n que una mujer m\u00e1s involucrada en el robo logr\u00f3 darse a la fuga con destino desconocido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Huejutla, Hgo. &#8211; Cuatro personas del sexo masculino y una mujer fueron asegurados por elementos de la polic\u00eda municipal tras haber perpetrado un asalto a un conocido negocio de comida. Los hechos ocurrieron presuntamente desde el pasado jueves en la cabecera municipal del municipio de Calnali, Hidalgo, cuando fue reportado a los elementos&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/26\/detienen-a-cinco-de-banda-delictiva\/\">Seguir leyendo <span class=\"screen-reader-text\">Detienen a cinco de banda delictiva<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":391035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181,178],"tags":[121],"class_list":["post-391034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","category-policiaca","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/391034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=391034"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/391034\/revisions"}],"predecessor-version":[{"id":391036,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/391034\/revisions\/391036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/391035"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=391034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=391034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=391034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}