{"id":391037,"date":"2021-08-27T00:17:18","date_gmt":"2021-08-27T05:17:18","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=391037"},"modified":"2021-08-27T00:17:19","modified_gmt":"2021-08-27T05:17:19","slug":"espejeando-por-perseo-46","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/27\/espejeando-por-perseo-46\/","title":{"rendered":"ESPEJEANDO Por Perseo"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">281<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F08%2F27%2Fespejeando-por-perseo-46%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/27\/espejeando-por-perseo-46\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\">Carolina Viggiano recorre la huasteca antes de irse unos meses a la curul de Diputada Federal, para en seguida, muy posiblemente, pedir licencia por su inter\u00e9s por competir por la gubernatura de Hidalgo, entre escenarios que van y vienen, pero Hidalgo es un laboratorio pol\u00edtico en el que suponen Andr\u00e9s Manuel L\u00f3pez Obrador arrebatar\u00eda el estado sin ning\u00fan contratiempo; por supuesto con Morena, su partido y el candidato que mejor les parezca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero vienen muchas coyunturas, como la necesidad de contar con un Congreso Federal que le permita avanzar, necesita aliados, con esto decimos que Hidalgo tendr\u00eda que ser uno de los estados que estar\u00e1n en la balanza de entre los seis en juego en el 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfEn Hidalgo pudiera surgir un PRIMOR? Todo puede pasar, en pol\u00edtica las hip\u00f3tesis van y vienen. Algunos albergan esa esperanza, otros radicalmente dicen que no, los m\u00e1s considerados explican que el senador de la rep\u00fablica Julio Ram\u00f3n Menchaca Salazar tiene nivel y car\u00e1cter para ser el eslab\u00f3n para de manera legitimada instalar el cambio democr\u00e1tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero dejemos que esto lo resuelvan los grupos pol\u00edticos de Hidalgo, el voto ciudadano solo habr\u00e1 de legitimar lo que quieren para el estado de Hidalgo, el instalar los perfiles en las trincheras que saldr\u00e1n al terreno pol\u00edtico a conquistar el voto, es solo parte del contexto. Morena est\u00e1 confiado en Hidalgo que cerrando filas nadie podr\u00e1 atentar contra la unidad; a menos de que les impongan un candidato externo desde el alto mando. Entonces\u2026 \u00bfqui\u00e9n ser\u00eda el institucional?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo puede pasar, en este momento solo se ve la polvareda de intereses en el aire, todos apuestan y aseguran, creen sue\u00f1an y perfilan a este, el otro, pero en pol\u00edtica nada es lo que parece, hay quien dice que el mismo Arturo Herrera podr\u00eda venir de la nada directo a retomar ese espacio, por supuesto son especulaciones, hip\u00f3tesis, todas muy v\u00e1lidas, se vale volar la imaginaci\u00f3n, porque finalmente en firme nadie tiene nada; solo aprecian la carta boca abajo del mandatario nacional \u2026\u2026\u2026\u2026. Parece que al l\u00edder de la Uni\u00f3n de Comerciantes, Locatarios, Tianguistas y Ambulantes Regi\u00f3n Huasteca (UCLTARH) Nicol\u00e1s Lara Herrera le encontraron el lado flaco, la regidora Ang\u00e9lica Cruz es una representante popular y por supuesto que la ley le asiste en cuanto a conocer lo que suceda dentro de los comerciantes, sean estos de la organizaci\u00f3n que sea, por supuesto que tiene injerencia en los temas de control y manipuleo que hay dentro de las organizaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es necesario que ponga la denuncia este l\u00edder para que le informen cu\u00e1l es la funci\u00f3n de una representante popular, velar por los intereses de los ciudadanos; lo que s\u00ed puede hacer la regidora es denunciar legalmente con esos agremiados inconformes, todas las irregularidades que consideren sean violatorias a derechos. El problema es la condici\u00f3n de v\u00edctimas de algunos comerciantes que por necesidad son sometidos por el inter\u00e9s de los dirigentes de comerciantes. Estos deben entender que ya no hay impunidad y que estar agremiado no puede condicionar a nadie, para algo, que el trabajo es libre, que tambi\u00e9n hay ley para los l\u00edderes que abusan impunemente de la ignorancia de las personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ojal\u00e1 el resto de regidores hicieran lo que ang\u00e9lica, defendieran derechos de los ciudadanos, pero no los vemos, no los escuchamos, bueno d\u00f3nde est\u00e1 la voz p\u00fablica de Margarito Monterrubio, no basta solo opinar en el cabildo, afuera hay mucho que ver y hacer; el PAN levanta la voz dentro de Cabildo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los regidores de Morena fueron los primeros que se pusieron firmes en el gobierno, de inmediato se cuadraron ante su jefe pol\u00edtico de la comuna, porque esa cantaleta p\u00fablica de honestidad y transparencia, pues es eso, mero protagonismo p\u00fablico, nada de trabajo social, de fondo o forma, nada de indigenismo, defensa del derecho p\u00fablico del ciudadano, ah\u00ed est\u00e1n sus comisiones intactas, los espacios en las calles siguen en manos de particulares, los temas de cultura siguen desaparecidos, la basura sigue siendo un problema, el agua potable es parte de un tema central, muy delicado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carolina Viggiano recorre la huasteca antes de irse unos meses a la curul de Diputada Federal, para en seguida, muy posiblemente, pedir licencia por su inter\u00e9s por competir por la gubernatura de Hidalgo, entre escenarios que van y vienen, pero Hidalgo es un laboratorio pol\u00edtico en el que suponen Andr\u00e9s Manuel L\u00f3pez Obrador arrebatar\u00eda el&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/27\/espejeando-por-perseo-46\/\">Seguir leyendo <span class=\"screen-reader-text\">ESPEJEANDO Por Perseo<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":391039,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[176],"tags":[205],"class_list":["post-391037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espejeando","tag-espejeando","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/391037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=391037"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/391037\/revisions"}],"predecessor-version":[{"id":391040,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/391037\/revisions\/391040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/391039"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=391037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=391037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=391037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}