{"id":391086,"date":"2021-08-27T15:46:54","date_gmt":"2021-08-27T20:46:54","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=391086"},"modified":"2021-08-27T15:46:55","modified_gmt":"2021-08-27T20:46:55","slug":"lider-del-pri-pide-mantener-la-unidad","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/27\/lider-del-pri-pide-mantener-la-unidad\/","title":{"rendered":"L\u00edder del PRI pide mantener la unidad"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">170<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F08%2F27%2Flider-del-pri-pide-mantener-la-unidad%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/27\/lider-del-pri-pide-mantener-la-unidad\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Roberto Meza\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Yahualica, Hgo.-<\/strong> El dirigente municipal del Partido Revolucionario Institucional (PRI), Abelino Bautista, pidi\u00f3 a todos los pri\u00edstas de Yahualica mantener la unidad, como siempre han trabajado, ya que de esa manera se mantendr\u00e1 la fuerza del organismo pol\u00edtico para las pr\u00f3ximas jornadas electorales que habr\u00e1n de enfrentar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que, independientemente de los resultados del pasado proceso electoral en el municipio, se busca que todas las corrientes de ese instituto pol\u00edtico est\u00e9n unidas y trabajando para los militantes, porque a trav\u00e9s de ello se lograr\u00e1n muchos prop\u00f3sitos; pidi\u00f3 sumarse a las acciones que actualmente se lleva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, invit\u00f3 a todos los pri\u00edstas a acercarse a las oficinas de dicho partido, para escuchar sus inquietudes y propuestas a fin de seguir trabajando para todos, ya que lo importante en estos tiempos es sumar a toda la militancia y buscar nuevos proyectos, sobre c\u00f3mo desempe\u00f1arse en los siguientes a\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Roberto Meza\/Zunoticia Yahualica, Hgo.- El dirigente municipal del Partido Revolucionario Institucional (PRI), Abelino Bautista, pidi\u00f3 a todos los pri\u00edstas de Yahualica mantener la unidad, como siempre han trabajado, ya que de esa manera se mantendr\u00e1 la fuerza del organismo pol\u00edtico para las pr\u00f3ximas jornadas electorales que habr\u00e1n de enfrentar. Dijo que, independientemente de los&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/27\/lider-del-pri-pide-mantener-la-unidad\/\">Seguir leyendo <span class=\"screen-reader-text\">L\u00edder del PRI pide mantener la unidad<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":391092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[179,203],"tags":[123],"class_list":["post-391086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huasteca","category-yahualica","tag-yahualica","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/391086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=391086"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/391086\/revisions"}],"predecessor-version":[{"id":391093,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/391086\/revisions\/391093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/391092"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=391086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=391086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=391086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}