{"id":391106,"date":"2021-08-27T16:42:52","date_gmt":"2021-08-27T21:42:52","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=391106"},"modified":"2021-08-27T16:42:53","modified_gmt":"2021-08-27T21:42:53","slug":"frecuente-capacitacion-para-la-cloracion-del-agua","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/27\/frecuente-capacitacion-para-la-cloracion-del-agua\/","title":{"rendered":"Frecuente capacitaci\u00f3n para la cloraci\u00f3n del agua"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">223<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F08%2F27%2Ffrecuente-capacitacion-para-la-cloracion-del-agua%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/27\/frecuente-capacitacion-para-la-cloracion-del-agua\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Roberto Meza\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huazalingo, Hgo.-<\/strong> Personal de la Coordinaci\u00f3n de Salud Municipal que preside Ferm\u00edn \u00c1lvarez, mencion\u00f3 que llevan de manera frecuente la capacitaci\u00f3n de los comit\u00e9s de agua potable y manantiales, de las comunidades sobre la cloraci\u00f3n, con el prop\u00f3sito de que limpien el vital l\u00edquido y la gente no padezca de enfermedades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe busca con esto resarcir los padecimientos gastrointestinales, por lo que a todos los asistentes se les explica el procedimiento de c\u00f3mo deben utilizar la cloraci\u00f3n en los tanques de almacenamiento, pozos, manantiales y dem\u00e1s recursos h\u00eddricos\u201d se\u00f1alaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se pretende que los integrantes de los comit\u00e9s de agua potable en todo el municipio sepan qu\u00e9 cantidad aplicar de cloro en el volumen de agua, ya que este debe ser con exactitud \u201ccon estas actividades todas las personas encargadas de clorar el agua en las localidades no tendr\u00e1n problema, as\u00ed mismo la gente podr\u00e1 consumirla sin problema\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Roberto Meza\/Zunoticia Huazalingo, Hgo.- Personal de la Coordinaci\u00f3n de Salud Municipal que preside Ferm\u00edn \u00c1lvarez, mencion\u00f3 que llevan de manera frecuente la capacitaci\u00f3n de los comit\u00e9s de agua potable y manantiales, de las comunidades sobre la cloraci\u00f3n, con el prop\u00f3sito de que limpien el vital l\u00edquido y la gente no padezca de enfermedades. \u201cSe&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/08\/27\/frecuente-capacitacion-para-la-cloracion-del-agua\/\">Seguir leyendo <span class=\"screen-reader-text\">Frecuente capacitaci\u00f3n para la cloraci\u00f3n del agua<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":391089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[179,212],"tags":[138],"class_list":["post-391106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huasteca","category-huazalingo","tag-huazalingo","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/391106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=391106"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/391106\/revisions"}],"predecessor-version":[{"id":391107,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/391106\/revisions\/391107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/391089"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=391106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=391106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=391106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}