{"id":392089,"date":"2021-09-03T19:45:26","date_gmt":"2021-09-04T00:45:26","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=392089"},"modified":"2021-09-03T19:45:27","modified_gmt":"2021-09-04T00:45:27","slug":"alcalde-se-compromete-trabajar-con-los-maestros-en-este-regreso-a-clases","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/03\/alcalde-se-compromete-trabajar-con-los-maestros-en-este-regreso-a-clases\/","title":{"rendered":"Alcalde se compromete trabajar con los maestros en este regreso a clases"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">14<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F03%2Falcalde-se-compromete-trabajar-con-los-maestros-en-este-regreso-a-clases%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/03\/alcalde-se-compromete-trabajar-con-los-maestros-en-este-regreso-a-clases\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Roberto Meza\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Atlapexco, Hgo. &#8211;<\/strong> Este viernes el alcalde Juli\u00e1n Nochebuena Hern\u00e1ndez, sostuvo una mesa de trabajo con representantes de las escuelas de este municipio, con la finalidad de trabajar coordinadamente para la prevenci\u00f3n del covid 19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento se desarroll\u00f3 en las oficinas de los servicios regionales de Atlapexco, estando presentes el titular de la Jurisdicci\u00f3n Sanitaria Abraham S\u00e1nchez, del profesor Gilberto Maldonado, entre otros funcionarios.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-03-at-6.33.17-PM-14-1024x682.jpeg\" alt=\"\" class=\"wp-image-392091\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-03-at-6.33.17-PM-14-1024x682.jpeg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-03-at-6.33.17-PM-14-300x200.jpeg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-03-at-6.33.17-PM-14-768x512.jpeg 768w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-03-at-6.33.17-PM-14.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El edil, se comprometi\u00f3 aplicar los esfuerzos con el sector salud para garantizar que las y los integrantes del sistema educativo tengan un regreso seguro a las aulas.&nbsp; Establecieron nuevos acuerdos para evitar contagios y salvaguardar la integridad de los atlapexquenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mun\u00edcipe dijo que la salud de los atlapexquenses siempre ser\u00e1 primero por eso es que ya se est\u00e1n sanitizando las escuelas y se dar\u00e1 todos los insumos para bien de los alumnos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Roberto Meza\/Zunoticia Atlapexco, Hgo. &#8211; Este viernes el alcalde Juli\u00e1n Nochebuena Hern\u00e1ndez, sostuvo una mesa de trabajo con representantes de las escuelas de este municipio, con la finalidad de trabajar coordinadamente para la prevenci\u00f3n del covid 19. El evento se desarroll\u00f3 en las oficinas de los servicios regionales de Atlapexco, estando presentes el titular&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/03\/alcalde-se-compromete-trabajar-con-los-maestros-en-este-regreso-a-clases\/\">Seguir leyendo <span class=\"screen-reader-text\">Alcalde se compromete trabajar con los maestros en este regreso a clases<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":392090,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[182],"tags":[133],"class_list":["post-392089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atlapexco","tag-atlapexco","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=392089"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392089\/revisions"}],"predecessor-version":[{"id":392092,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392089\/revisions\/392092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/392090"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=392089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=392089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=392089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}