{"id":392381,"date":"2021-09-05T22:41:50","date_gmt":"2021-09-06T03:41:50","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=392381"},"modified":"2021-09-05T22:41:51","modified_gmt":"2021-09-06T03:41:51","slug":"familia-casi-muere-por-intoxicacion-de-gas-lp","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/05\/familia-casi-muere-por-intoxicacion-de-gas-lp\/","title":{"rendered":"Familia casi muere por intoxicaci\u00f3n de gas LP"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">52<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F05%2Ffamilia-casi-muere-por-intoxicacion-de-gas-lp%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/05\/familia-casi-muere-por-intoxicacion-de-gas-lp\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo.- <\/strong>Cuatro personas del sexo femenino, entre ellas una menor de edad, estuvieron a punto de morir tras inhalar gas LP en el interior de su domicilio, por lo que fueron auxiliados por rescatistas de bomberos y param\u00e9dicos de cruz roja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los hechos ocurrieron la ma\u00f1ana del domingo alrededor de las 9:00 horas sobre la calle Principal de la colonia Parque Industrial, cuando las diferentes corporaciones de auxilio y polic\u00edacas fueron movilizados por integrantes de una familia, quienes se hab\u00edan intoxicado al haber inhalado Gas LP mientras dorm\u00edan, por lo que r\u00e1pidamente los cuerpos de emergencia se trasladaron hasta el domicilio particular.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"686\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-05-at-10.22.47-PM-1024x686.jpeg\" alt=\"\" class=\"wp-image-392374\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-05-at-10.22.47-PM-1024x686.jpeg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-05-at-10.22.47-PM-300x201.jpeg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-05-at-10.22.47-PM-768x514.jpeg 768w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-05-at-10.22.47-PM.jpeg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption><em> Cuatro personas fueron auxiliadas por rescatistas de bomberos y param\u00e9dicos de Cruz Roja.<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Al arribar al lugar le brindaron los primeros auxilios a una menor de 11 a\u00f1os, una mujer de 27 a\u00f1os con s\u00edndrome de down y dos mujeres adultas m\u00e1s, quienes despu\u00e9s de ser valoradas fueron trasladadas a una cl\u00ednica particular para recibir atenci\u00f3n m\u00e9dica, de igual manera, la propietaria de la vivienda de nombre M.F.H.B coment\u00f3 que alrededor de las 4 de horas de la madrugada despert\u00f3 para calentar caf\u00e9 en la estufa, sin embargo, no se percat\u00f3 que dejo la perilla abierta, por donde el gas comenz\u00f3 a escapar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed mismo, el cuerpo de bomberos acudi\u00f3 para identificar de d\u00f3nde proven\u00eda el gas y posteriormente dieron las recomendaciones correspondientes mientras que la polic\u00eda municipal tom\u00f3 conocimiento de lo sucedido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Huejutla, Hgo.- Cuatro personas del sexo femenino, entre ellas una menor de edad, estuvieron a punto de morir tras inhalar gas LP en el interior de su domicilio, por lo que fueron auxiliados por rescatistas de bomberos y param\u00e9dicos de cruz roja. Los hechos ocurrieron la ma\u00f1ana del domingo alrededor de las 9:00&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/05\/familia-casi-muere-por-intoxicacion-de-gas-lp\/\">Seguir leyendo <span class=\"screen-reader-text\">Familia casi muere por intoxicaci\u00f3n de gas LP<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":392373,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[179,178],"tags":[121],"class_list":["post-392381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huasteca","category-policiaca","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=392381"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392381\/revisions"}],"predecessor-version":[{"id":392382,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392381\/revisions\/392382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/392373"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=392381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=392381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=392381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}