{"id":392843,"date":"2021-09-09T22:02:06","date_gmt":"2021-09-10T03:02:06","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=392843"},"modified":"2021-09-09T22:02:07","modified_gmt":"2021-09-10T03:02:07","slug":"piden-a-la-administradora-del-mercado-que-sancionen-a-quienes-roban-energia-electrica","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/09\/piden-a-la-administradora-del-mercado-que-sancionen-a-quienes-roban-energia-electrica\/","title":{"rendered":"Piden a la administradora del mercado que sancionen a quienes roban energ\u00eda el\u00e9ctrica"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">20<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F09%2Fpiden-a-la-administradora-del-mercado-que-sancionen-a-quienes-roban-energia-electrica%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/09\/piden-a-la-administradora-del-mercado-que-sancionen-a-quienes-roban-energia-electrica\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Salvador Altamirano\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo. &#8211;<\/strong> Locatarios ubicados en el interior del mercado municipal exhortan a la administradora del inmueble, Lidia Vite Cruz, para que se sancione a los compa\u00f1eros que se sorprenda &#8220;robando luz&#8221;, lo cual es muy generalizado en el complejo comercial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agregaron que, como representante del ayuntamiento tiene la facultad de hacerlo, ya que no nada m\u00e1s se hurtan la energ\u00eda el\u00e9ctrica de los medidores particulares, tambi\u00e9n la de car\u00e1cter p\u00fablico, cuyo recibo lo liquida el municipio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Subrayaron que la conexi\u00f3n de los &#8220;cl\u00e1sicos diablitos&#8221;, es una pr\u00e1ctica de robo muy generalizada desde ya hace much\u00edsimos a\u00f1os entre los comerciantes, por lo que el mercado municipal est\u00e1 considerado por las autoridades estatales de Protecci\u00f3n civil, tambi\u00e9n desde hace bastante tiempo, como &#8220;foco rojo&#8221; o sea de alto riesgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, comentaron ese a\u00f1ejo y peligroso problema, no lo ha querido enfrentar ning\u00fan exdirigente de la UCLA, y no creemos que el actual sea la excepci\u00f3n, ya que siempre argumentaron para evadir su responsabilidad que compete al municipio\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para finalizar, enfatizaron que otro de los peligros latentes en el mercado municipal, en especial en la nave central y accesos de la misma tambi\u00e9n desde hace a\u00f1os, es la obstrucci\u00f3n de pasillos, dificultad a la que &#8220;tienen temor de meterle mano&#8221;, mientras tanto, locatarios y clientes, afrontan a diario el peligro de una tragedia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Salvador Altamirano\/Zunoticia Huejutla, Hgo. &#8211; Locatarios ubicados en el interior del mercado municipal exhortan a la administradora del inmueble, Lidia Vite Cruz, para que se sancione a los compa\u00f1eros que se sorprenda &#8220;robando luz&#8221;, lo cual es muy generalizado en el complejo comercial. Agregaron que, como representante del ayuntamiento tiene la facultad de hacerlo,&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/09\/piden-a-la-administradora-del-mercado-que-sancionen-a-quienes-roban-energia-electrica\/\">Seguir leyendo <span class=\"screen-reader-text\">Piden a la administradora del mercado que sancionen a quienes roban energ\u00eda el\u00e9ctrica<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":392844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-392843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=392843"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392843\/revisions"}],"predecessor-version":[{"id":392845,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392843\/revisions\/392845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/392844"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=392843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=392843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=392843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}