{"id":392882,"date":"2021-09-09T22:29:30","date_gmt":"2021-09-10T03:29:30","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=392882"},"modified":"2021-09-09T22:29:32","modified_gmt":"2021-09-10T03:29:32","slug":"dif-dona-medicamentos-a-la-poblacion","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/09\/dif-dona-medicamentos-a-la-poblacion\/","title":{"rendered":"DIF dona medicamentos a la poblaci\u00f3n"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">24<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F09%2Fdif-dona-medicamentos-a-la-poblacion%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/09\/dif-dona-medicamentos-a-la-poblacion\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Roberto Meza\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Yahualica, Hgo. &#8211;<\/strong> La titular del DIF local Patricia Rodr\u00edguez Murillo, dijo que se les est\u00e1 apoyando con medicamentos a toda la poblaci\u00f3n que as\u00ed lo necesita, los pacientes que se les dota de estas medicinas son los que acuden a consulta externa en casas de salud, as\u00ed mismo dijo que se est\u00e1 dotando de medicamentos a la gente de las comunidades a trav\u00e9s de las representantes de DIF.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La funcionaria agreg\u00f3 que esto es con la finalidad de apoyar a todas las personas principalmente a aquellos que no pueden comprar sus medicinas para su tratamiento, por eso es que se les entrega de acuerdo a su receta m\u00e9dica que presente, para que as\u00ed puedan atender el tratamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para terminar la titular del DIF, pronunci\u00f3 que en breve tambi\u00e9n entregaran aparatos funcionales, gestiones que ya se llevaron y ya solo se espera que los apoyos lleguen para los sectores m\u00e1s vulnerables de este municipio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Roberto Meza\/Zunoticia Yahualica, Hgo. &#8211; La titular del DIF local Patricia Rodr\u00edguez Murillo, dijo que se les est\u00e1 apoyando con medicamentos a toda la poblaci\u00f3n que as\u00ed lo necesita, los pacientes que se les dota de estas medicinas son los que acuden a consulta externa en casas de salud, as\u00ed mismo dijo que se&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/09\/dif-dona-medicamentos-a-la-poblacion\/\">Seguir leyendo <span class=\"screen-reader-text\">DIF dona medicamentos a la poblaci\u00f3n<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":392883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[179,203],"tags":[123],"class_list":["post-392882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huasteca","category-yahualica","tag-yahualica","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=392882"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392882\/revisions"}],"predecessor-version":[{"id":392884,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392882\/revisions\/392884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/392883"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=392882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=392882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=392882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}