{"id":392954,"date":"2021-09-10T14:26:11","date_gmt":"2021-09-10T19:26:11","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=392954"},"modified":"2021-09-10T14:26:14","modified_gmt":"2021-09-10T19:26:14","slug":"el-gobierno-de-orizatlan-continua-con-los-trabajos-en-el-basurero-municipal","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/el-gobierno-de-orizatlan-continua-con-los-trabajos-en-el-basurero-municipal\/","title":{"rendered":"El gobierno de Orizatl\u00e1n contin\u00faa con los trabajos en el basurero municipal"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">31<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F10%2Fel-gobierno-de-orizatlan-continua-con-los-trabajos-en-el-basurero-municipal%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/el-gobierno-de-orizatlan-continua-con-los-trabajos-en-el-basurero-municipal\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>San Felipe Orizatl\u00e1n, Hgo.-<\/strong> Con el prop\u00f3sito de cumplir con el proceso de compactaci\u00f3n que se debe otorgar a los residuos s\u00f3lidos, la administraci\u00f3n municipal que preside Erika Saab Lara, a trav\u00e9s del \u00e1rea de Servicios Municipales, contin\u00faa llevando a cabo los trabajos de relleno sanitario en el basurero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas actividades se est\u00e1n realizando con una m\u00e1quina que est\u00e1 cubriendo los desechos con tierra para compactar el terreno y formar capas que permitan seguir alargando la vida del basurero municipal, a fin de que se puedan seguir depositando la basura que diariamente genera la poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con estas acciones se busca cumplir con el proceso de degradaci\u00f3n de basura y con ello, contribuir con el medio ambiente y los recursos naturales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia. San Felipe Orizatl\u00e1n, Hgo.- Con el prop\u00f3sito de cumplir con el proceso de compactaci\u00f3n que se debe otorgar a los residuos s\u00f3lidos, la administraci\u00f3n municipal que preside Erika Saab Lara, a trav\u00e9s del \u00e1rea de Servicios Municipales, contin\u00faa llevando a cabo los trabajos de relleno sanitario en el basurero. Estas actividades se est\u00e1n&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/el-gobierno-de-orizatlan-continua-con-los-trabajos-en-el-basurero-municipal\/\">Seguir leyendo <span class=\"screen-reader-text\">El gobierno de Orizatl\u00e1n contin\u00faa con los trabajos en el basurero municipal<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":392955,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[179,180],"tags":[129],"class_list":["post-392954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huasteca","category-orizatlan","tag-orizatlan","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=392954"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392954\/revisions"}],"predecessor-version":[{"id":392956,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392954\/revisions\/392956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/392955"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=392954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=392954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=392954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}