{"id":392973,"date":"2021-09-10T15:49:09","date_gmt":"2021-09-10T20:49:09","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=392973"},"modified":"2021-09-10T15:49:09","modified_gmt":"2021-09-10T20:49:09","slug":"edil-inauguro-pavimentacion-de-concreto-hidraulico-en-amaxac","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/edil-inauguro-pavimentacion-de-concreto-hidraulico-en-amaxac\/","title":{"rendered":"Edil inaugur\u00f3 pavimentaci\u00f3n de concreto hidr\u00e1ulico en Amaxac"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">19<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F10%2Fedil-inauguro-pavimentacion-de-concreto-hidraulico-en-amaxac%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/edil-inauguro-pavimentacion-de-concreto-hidraulico-en-amaxac\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Roberto Meza\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huazalingo, Hgo.-<\/strong> El presidente municipal Julio C\u00e9sar Gonz\u00e1lez Garc\u00eda, la tarde de este viernes efect\u00fao una gira de trabajo por la comunidad de Amaxac, para inaugurar una obra de pavimentaci\u00f3n hidr\u00e1ulica con importante derrama econ\u00f3mica, con esto busca propiciar mejores condiciones de vida para todos los habitantes de esa demarcaci\u00f3n poblacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mun\u00edcipe fue recibido por las autoridades delegacionales y ejidales, le dieron la bienvenida con las tradiciones de ese pueblo con coronas y collares de flores, como una muestra de agradecimiento por esta obra que se llev\u00f3 a cabo en estos \u00faltimos meses; el presidente junto con sus acompa\u00f1antes cort\u00f3 el list\u00f3n inaugural de dicha obra.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"497\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/eZy-Watermark-10-09-2021-03-38-12p.m..jpg\" alt=\"\" class=\"wp-image-392975\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/eZy-Watermark-10-09-2021-03-38-12p.m..jpg 720w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/eZy-Watermark-10-09-2021-03-38-12p.m.-300x207.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El jefe de la comuna al enviar su mensaje ante los presentes dijo \u201cse cumpli\u00f3 con una obra que tiene un costo de 788,337.96 pesos, habr\u00e1 de beneficiar a todos los pobladores y que las autoridades la aprobaron como prioritaria\u201d, expresando que de esta manera se est\u00e1 trabajando en todo el municipio, llevando las obras de gran impacto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Roberto Meza\/Zunoticia Huazalingo, Hgo.- El presidente municipal Julio C\u00e9sar Gonz\u00e1lez Garc\u00eda, la tarde de este viernes efect\u00fao una gira de trabajo por la comunidad de Amaxac, para inaugurar una obra de pavimentaci\u00f3n hidr\u00e1ulica con importante derrama econ\u00f3mica, con esto busca propiciar mejores condiciones de vida para todos los habitantes de esa demarcaci\u00f3n poblacional. El&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/edil-inauguro-pavimentacion-de-concreto-hidraulico-en-amaxac\/\">Seguir leyendo <span class=\"screen-reader-text\">Edil inaugur\u00f3 pavimentaci\u00f3n de concreto hidr\u00e1ulico en Amaxac<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":392974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[179,212],"tags":[138],"class_list":["post-392973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huasteca","category-huazalingo","tag-huazalingo","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=392973"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392973\/revisions"}],"predecessor-version":[{"id":392976,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392973\/revisions\/392976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/392974"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=392973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=392973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=392973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}