{"id":392990,"date":"2021-09-10T16:55:46","date_gmt":"2021-09-10T21:55:46","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=392990"},"modified":"2021-09-10T16:55:47","modified_gmt":"2021-09-10T21:55:47","slug":"registros-destapados-son-un-riesgo-para-la-salud","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/registros-destapados-son-un-riesgo-para-la-salud\/","title":{"rendered":"Registros destapados son un riesgo para la salud"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">24<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F10%2Fregistros-destapados-son-un-riesgo-para-la-salud%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/registros-destapados-son-un-riesgo-para-la-salud\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Francisco Rosas\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo.-<\/strong> Vecinos de la colonia Magisterial y sectores aleda\u00f1os, denuncian que en el margen del r\u00edo hay varios registros de drenaje destapados, lo cual representa un riesgo para la salud, debido a los f\u00e9tidos olores que producen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Griselda Hern\u00e1ndez Antol\u00edn, quien dijo tener su domicilio en esta zona poblacional, manifest\u00f3 que desde que se robaron las tapas de metal, hasta el momento los registros de drenaje que se encuentran en la ribera del afluente permanecen abiertos, lo que representa un foco de infecci\u00f3n, adem\u00e1s de la reproducci\u00f3n de moscas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que, hasta el momento las autoridades correspondientes no han hecho nada al respecto, por lo que persisten los f\u00e9tidos olores, situaci\u00f3n por la cual piden que repongan las tapas por unas de concreto para que no se las vuelvan a robar y se solucione el problema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Francisco Rosas\/Zunoticia Huejutla, Hgo.- Vecinos de la colonia Magisterial y sectores aleda\u00f1os, denuncian que en el margen del r\u00edo hay varios registros de drenaje destapados, lo cual representa un riesgo para la salud, debido a los f\u00e9tidos olores que producen. Griselda Hern\u00e1ndez Antol\u00edn, quien dijo tener su domicilio en esta zona poblacional, manifest\u00f3 que&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/registros-destapados-son-un-riesgo-para-la-salud\/\">Seguir leyendo <span class=\"screen-reader-text\">Registros destapados son un riesgo para la salud<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":392991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-392990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=392990"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392990\/revisions"}],"predecessor-version":[{"id":392992,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/392990\/revisions\/392992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/392991"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=392990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=392990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=392990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}