{"id":393002,"date":"2021-09-10T18:53:12","date_gmt":"2021-09-10T23:53:12","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=393002"},"modified":"2021-09-10T18:53:13","modified_gmt":"2021-09-10T23:53:13","slug":"parroquias-de-la-diocesis-realizan-colecta-economica-para-ayudar-al-pueblo-de-tula","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/parroquias-de-la-diocesis-realizan-colecta-economica-para-ayudar-al-pueblo-de-tula\/","title":{"rendered":"Parroquias de la di\u00f3cesis realizan colecta econ\u00f3mica para ayudar al pueblo de Tula"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">0<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F10%2Fparroquias-de-la-diocesis-realizan-colecta-economica-para-ayudar-al-pueblo-de-tula%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/parroquias-de-la-diocesis-realizan-colecta-economica-para-ayudar-al-pueblo-de-tula\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Enedino Hern\u00e1ndez\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo. &#8211;<\/strong> \u201cDesde el jueves 9 y hasta el domingo 12 de septiembre, en cada una de las parroquias de la Di\u00f3cesis de Huejutla de Reyes se llevar\u00e1 a cabo una colecta econ\u00f3mica con la cual se busca ayudar a los damnificados de Tula\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior fue confirmado por el vocero de la Di\u00f3cesis de Huejutla, Jes\u00fas Morfin Cartagena qui\u00e9n consider\u00f3 que es el momento de poner la mirada en las principales necesidades que tienen las personas, y que realmente sufren m\u00e1s que nosotros, \u201ctodos somos pobres, todos sufrimos, pero hay desastres naturales que hacen sufrir mucho m\u00e1s a las familias\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abund\u00f3 \u201cen un primer momento, todos podemos hacer oraci\u00f3n por el pueblo de Tula, esto es algo efectivamente muy importante, la oraci\u00f3n, y por otro lado en lo que corresponde a la Di\u00f3cesis de Huejutla se realiza una colecta econ\u00f3mica para poder ayudar a las familias que en estos momentos lo requieren\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Detall\u00f3 que la colecta econ\u00f3mica se realizar\u00e1 del 9 al 12 de septiembre y tiene como finalidad el apoyar a las familias damnificadas que se tienen en Tula, considerando que la poblaci\u00f3n puede participar de acuerdo a sus posibilidades, para ayudar a estos hermanos que hoy lo necesitan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00f1adi\u00f3 que, la poblaci\u00f3n que quiera solidarizarse con esta colecta puede hacer llegar su donativo a cualquiera de las parroquias de la Di\u00f3cesis de Huejutla o en su caso acudir a las oficinas del Obispado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Enedino Hern\u00e1ndez\/Zunoticia Huejutla, Hgo. &#8211; \u201cDesde el jueves 9 y hasta el domingo 12 de septiembre, en cada una de las parroquias de la Di\u00f3cesis de Huejutla de Reyes se llevar\u00e1 a cabo una colecta econ\u00f3mica con la cual se busca ayudar a los damnificados de Tula\u201d. Lo anterior fue confirmado por el vocero&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/parroquias-de-la-diocesis-realizan-colecta-economica-para-ayudar-al-pueblo-de-tula\/\">Seguir leyendo <span class=\"screen-reader-text\">Parroquias de la di\u00f3cesis realizan colecta econ\u00f3mica para ayudar al pueblo de Tula<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":393003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-393002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=393002"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393002\/revisions"}],"predecessor-version":[{"id":393004,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393002\/revisions\/393004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/393003"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=393002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=393002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=393002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}