{"id":393015,"date":"2021-09-10T20:03:19","date_gmt":"2021-09-11T01:03:19","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=393015"},"modified":"2021-09-10T20:03:20","modified_gmt":"2021-09-11T01:03:20","slug":"si-habra-festejo-patrio-con-aforo-reducido-y-transmision-en-redes-sociales","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/si-habra-festejo-patrio-con-aforo-reducido-y-transmision-en-redes-sociales\/","title":{"rendered":"Si habr\u00e1 festejo patrio con aforo reducido y transmisi\u00f3n en redes sociales"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">35<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F10%2Fsi-habra-festejo-patrio-con-aforo-reducido-y-transmision-en-redes-sociales%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/si-habra-festejo-patrio-con-aforo-reducido-y-transmision-en-redes-sociales\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por \u00c1ngel Silverio\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>San Felipe Orizatl\u00e1n, Hgo. &#8211;<\/strong> Con el fin de no pasar desapercibido las fiestas patrias que est\u00e1n pr\u00f3ximas a celebrarse, la alcaldesa Erika Saab Lara, indic\u00f3 que se realizar\u00e1n bajo todos los protocolos de seguridad que indican las autoridades de salud, as\u00ed como a trav\u00e9s de las redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En entrevista con este medio, al cuestionarle sobre si habr\u00e1 o no festejos patrios, Saab Lara, puntualiz\u00f3, &#8211; \u201cLa verdad es que nosotros hemos sido muy cuidadosos de obviamente cumplir con todas las recomendaciones que nos hacen las autoridades sanitarias, en este caso sabemos que la propia secretaria de salud ha emitido en el periodo oficial cuales son los eventos que se pueden y que no se pueden llevar a cabo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, dijo que en ese sentido por supuesto que pueden hacer un evento, &#8211; \u201cCon m\u00ednima y m\u00e1xima y lo vamos a hacer justamente as\u00ed en la explanada municipal que es al aire libre, con todos los protocolos, con un p\u00fablico muy cerrado, la explanada nos da para tener 150 a 200 personas m\u00e1ximas para poder celebrar el orgullo de nuestras fiestas patria, y tambi\u00e9n podr\u00e1n seguir los eventos en redes sociales del ayuntamiento\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, la alcaldesa continu\u00f3 invitando a la ciudadan\u00eda a que se sigan cuidando, &#8211; \u201cQue cumplamos las medidas de bioseguridad, usar el cubrebocas, la sana distancia, los que tengan la edad que asistan a vacunarse, para salir m\u00e1s r\u00e1pido de esto y cuidarnos todos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por \u00c1ngel Silverio\/Zunoticia San Felipe Orizatl\u00e1n, Hgo. &#8211; Con el fin de no pasar desapercibido las fiestas patrias que est\u00e1n pr\u00f3ximas a celebrarse, la alcaldesa Erika Saab Lara, indic\u00f3 que se realizar\u00e1n bajo todos los protocolos de seguridad que indican las autoridades de salud, as\u00ed como a trav\u00e9s de las redes sociales. En entrevista con&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/si-habra-festejo-patrio-con-aforo-reducido-y-transmision-en-redes-sociales\/\">Seguir leyendo <span class=\"screen-reader-text\">Si habr\u00e1 festejo patrio con aforo reducido y transmisi\u00f3n en redes sociales<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":393016,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[180],"tags":[230],"class_list":["post-393015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orizatlan","tag-orizatlan-2","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=393015"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393015\/revisions"}],"predecessor-version":[{"id":393017,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393015\/revisions\/393017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/393016"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=393015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=393015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=393015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}