{"id":393025,"date":"2021-09-10T22:29:33","date_gmt":"2021-09-11T03:29:33","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=393025"},"modified":"2021-09-10T22:29:35","modified_gmt":"2021-09-11T03:29:35","slug":"sin-obras-de-impacto-a-casi-un-ano-de-gobierno-ciudadanos","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/sin-obras-de-impacto-a-casi-un-ano-de-gobierno-ciudadanos\/","title":{"rendered":"Sin obras de impacto, a casi un a\u00f1o de gobierno: Ciudadanos"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">37<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F10%2Fsin-obras-de-impacto-a-casi-un-ano-de-gobierno-ciudadanos%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/sin-obras-de-impacto-a-casi-un-ano-de-gobierno-ciudadanos\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por \u00c1ngel Silverio\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jaltoc\u00e1n, Hgo. &#8211;<\/strong> A unos cuantos meses de cumplir su primero a\u00f1o de gobierno, tomando en cuenta que entraron en funciones los ayuntamientos municipales en el mes de diciembre, fue anunciado que ser\u00e1 la pr\u00f3xima semana cuando se rinda el primer informe de actividades de la actual administraci\u00f3n, lo que caus\u00f3 inmediatamente reacciones entre la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a lo que fue dado a conocer, la administraci\u00f3n del alcalde Iv\u00e1n Lara Tovar, realizar\u00e1 la transmisi\u00f3n en vivo del primer Informe de Gobierno sobre el estado que guarda la administraci\u00f3n p\u00fablica, y ser\u00e1 este pr\u00f3ximo s\u00e1bado 18 de septiembre a las 10 de la ma\u00f1ana a trav\u00e9s de la plataforma oficial del ayuntamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, tras darse a conocer la noticia, ciudadanos en la cabecera municipal, han externado su inconformidad, pues aseguran que a casi un a\u00f1o de haber entrado en funciones, las cosas en el municipio no mejora, y s\u00f3lo intentan \u201ctapar el sol con un dedo\u201d pues obras realmente de impacto no se han presentado, e incluso aun cuando ya est\u00e1n construidas siguen con el celo pol\u00edtico, tal como lo es el sistema de agua potable, construido hace algunos a\u00f1os, con una inversi\u00f3n de 100 millones de pesos, y que simplemente no est\u00e1 en funci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra de las quejas, son las calles que se encuentran en el abandono, y que generan da\u00f1os en los veh\u00edculos, as\u00ed como tambi\u00e9n la principal queja en la cabecera municipal, es que esta administraci\u00f3n no ha hecho nada por evitar la contaminaci\u00f3n del r\u00edo debido a un drenaje inconcluso, y que se ha convertido en un foco de infecci\u00f3n y se salud p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por \u00c1ngel Silverio\/Zunoticia Jaltoc\u00e1n, Hgo. &#8211; A unos cuantos meses de cumplir su primero a\u00f1o de gobierno, tomando en cuenta que entraron en funciones los ayuntamientos municipales en el mes de diciembre, fue anunciado que ser\u00e1 la pr\u00f3xima semana cuando se rinda el primer informe de actividades de la actual administraci\u00f3n, lo que caus\u00f3 inmediatamente&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/sin-obras-de-impacto-a-casi-un-ano-de-gobierno-ciudadanos\/\">Seguir leyendo <span class=\"screen-reader-text\">Sin obras de impacto, a casi un a\u00f1o de gobierno: Ciudadanos<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":393026,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[179,200],"tags":[131],"class_list":["post-393025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huasteca","category-jaltocan","tag-jaltocan","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=393025"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393025\/revisions"}],"predecessor-version":[{"id":393027,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393025\/revisions\/393027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/393026"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=393025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=393025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=393025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}