{"id":393040,"date":"2021-09-10T22:35:24","date_gmt":"2021-09-11T03:35:24","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=393040"},"modified":"2021-09-10T22:35:25","modified_gmt":"2021-09-11T03:35:25","slug":"diocesis-de-huejutla-alerta-por-presuntos-estafadores","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/diocesis-de-huejutla-alerta-por-presuntos-estafadores\/","title":{"rendered":"Di\u00f3cesis de Huejutla alerta por presuntos estafadores"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">52<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F10%2Fdiocesis-de-huejutla-alerta-por-presuntos-estafadores%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/diocesis-de-huejutla-alerta-por-presuntos-estafadores\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo. &#8211;<\/strong> Jos\u00e9 Hir\u00e1is Acosta Beltr\u00e1n, obispo de Huejutla, a trav\u00e9s de un comunicado alert\u00f3 a la poblaci\u00f3n por presuntos estafadores a nombre de la di\u00f3cesis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su mensaje comunic\u00f3 que hay personas que han estado pidiendo apoyo para ayudar a la salud del P. Sim\u00f3n Hern\u00e1ndez Alvarado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las parroquias de Zacualtip\u00e1n, Hgo. y la Di\u00f3cesis de Huejutla, se deslindan de tal acci\u00f3n, pues al Padre Sim\u00f3n se le ha estado atendiendo \u201cy no hemos tenido la necesidad de pedir alg\u00fan apoyo para \u00e9l o alg\u00fan otro sacerdote\u201d, indic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicho comunicado es firmado por el se\u00f1or Obispo y por el Secretario Canciller, Israel Arriaga Flores, dejando en evidencia las malas acciones de maleantes y aclarando que no se est\u00e1 pidiendo dicha ayuda, exhortando a la poblaci\u00f3n a evitar hacer alguna donaci\u00f3n econ\u00f3mica y denunciar cualquier anomal\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Huejutla, Hgo. &#8211; Jos\u00e9 Hir\u00e1is Acosta Beltr\u00e1n, obispo de Huejutla, a trav\u00e9s de un comunicado alert\u00f3 a la poblaci\u00f3n por presuntos estafadores a nombre de la di\u00f3cesis. En su mensaje comunic\u00f3 que hay personas que han estado pidiendo apoyo para ayudar a la salud del P. Sim\u00f3n Hern\u00e1ndez Alvarado. Las parroquias de Zacualtip\u00e1n,&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/10\/diocesis-de-huejutla-alerta-por-presuntos-estafadores\/\">Seguir leyendo <span class=\"screen-reader-text\">Di\u00f3cesis de Huejutla alerta por presuntos estafadores<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":393042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181,178,1],"tags":[121],"class_list":["post-393040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","category-policiaca","category-sin-categoria","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=393040"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393040\/revisions"}],"predecessor-version":[{"id":393041,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393040\/revisions\/393041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/393042"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=393040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=393040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=393040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}