{"id":393120,"date":"2021-09-11T19:51:06","date_gmt":"2021-09-12T00:51:06","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=393120"},"modified":"2021-09-11T19:51:07","modified_gmt":"2021-09-12T00:51:07","slug":"a-174-anos-de-la-gesta-de-los-ninos-heroes","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/11\/a-174-anos-de-la-gesta-de-los-ninos-heroes\/","title":{"rendered":"A 174 a\u00f1os de la gesta de los &#8220;Ni\u00f1os H\u00e9roes&#8221;"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">21<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F11%2Fa-174-anos-de-la-gesta-de-los-ninos-heroes%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/11\/a-174-anos-de-la-gesta-de-los-ninos-heroes\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Salvador Altamirano\/Zunoticia&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo. &#8211;<\/strong> Manuel L\u00f3pez, quien dijo ser docente de una instituci\u00f3n primaria, manifest\u00f3 que el pr\u00f3ximo lunes se cumplen 174 a\u00f1os de la gesta de los &#8220;Ni\u00f1os H\u00e9roes&#8221;, un acontecimiento hist\u00f3rico que debe de transmitirse a las nuevas generaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Especific\u00f3 \u201cse les llama Ni\u00f1os H\u00e9roes a un grupo de seis cadetes mexicanos que ofrendaron su vida en la Batalla de Chapultepec, el 13 de septiembre de 1847, durante la intervenci\u00f3n estadounidense en M\u00e9xico\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que la historia oficial fue publicada por primera vez en el a\u00f1o de 1852, pero con m\u00e1s notoriedad y mayores datos desde la segunda mitad del siglo XIX, colocando en esta denominaci\u00f3n a 6 cadetes del Ej\u00e9rcito Mexicano: Agust\u00edn Melgar, Fernando Montes de Oca, Juan de la Barrera, Francisco M\u00e1rquez, Juan Escutia y Vicente Su\u00e1rez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfatiz\u00f3 que el argumento oficial del acto heroico refiere que estos seis cadetes y 40 m\u00e1s, recibieron del General Nicol\u00e1s Bravo la orden de que abandonaran de inmediato el Castillo de Chapultepec, en ese entonces sede del Colegio Militar, sin embargo, decidieron quedarse a defender la plaza ante el avance del Ej\u00e9rcito de Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para concluir, enfatiz\u00f3 que en un merecido homenaje en el boulevard Adolfo L\u00f3pez Mateos, de la colonia Aviaci\u00f3n Civil, hay un hemiciclo a los Ni\u00f1os H\u00e9roes, el cual es un icono similar al que est\u00e1 en la entrada principal del parque de Chapultepec, en la Ciudad de M\u00e9xico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Salvador Altamirano\/Zunoticia&nbsp; Huejutla, Hgo. &#8211; Manuel L\u00f3pez, quien dijo ser docente de una instituci\u00f3n primaria, manifest\u00f3 que el pr\u00f3ximo lunes se cumplen 174 a\u00f1os de la gesta de los &#8220;Ni\u00f1os H\u00e9roes&#8221;, un acontecimiento hist\u00f3rico que debe de transmitirse a las nuevas generaciones. Especific\u00f3 \u201cse les llama Ni\u00f1os H\u00e9roes a un grupo de seis cadetes&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/11\/a-174-anos-de-la-gesta-de-los-ninos-heroes\/\">Seguir leyendo <span class=\"screen-reader-text\">A 174 a\u00f1os de la gesta de los &#8220;Ni\u00f1os H\u00e9roes&#8221;<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":393121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-393120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=393120"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393120\/revisions"}],"predecessor-version":[{"id":393122,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393120\/revisions\/393122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/393121"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=393120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=393120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=393120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}