{"id":393172,"date":"2021-09-12T14:46:15","date_gmt":"2021-09-12T19:46:15","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=393172"},"modified":"2021-09-12T14:46:16","modified_gmt":"2021-09-12T19:46:16","slug":"descontrol-en-instalacion-de-filtros-sanitizantes-en-accesos-al-tianguis","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/12\/descontrol-en-instalacion-de-filtros-sanitizantes-en-accesos-al-tianguis\/","title":{"rendered":"Descontrol en instalaci\u00f3n de filtros sanitizantes en accesos al tianguis"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">27<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F12%2Fdescontrol-en-instalacion-de-filtros-sanitizantes-en-accesos-al-tianguis%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/12\/descontrol-en-instalacion-de-filtros-sanitizantes-en-accesos-al-tianguis\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Salvador Altamirano\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo. &#8211;<\/strong> De acuerdo a la relaci\u00f3n de control en los filtros sanitizantes de accesos al tianguis y mercado municipal, compartida entre el Sector Salud, gremios de comerciantes y personal adscrito al municipio, este domingo le correspondi\u00f3 a los \u00faltimos, denot\u00e1ndose cierto descontrol en lo que respecta a su vital responsabilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos de los accesos m\u00e1s concurridos, son el de las calles Hilario Men\u00edndez y Sonora, en la primera no se instal\u00f3 la cabina sanitizante y en la segunda s\u00ed, pero estaba sin personal, no asistieron a quienes les correspond\u00eda cuidar en ambas entradas, lo que llam\u00f3 de inmediato la atenci\u00f3n de quienes ingresaban al complejo comercial.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-12-at-2.21.52-PM-1024x576.jpeg\" alt=\"\" class=\"wp-image-393175\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-12-at-2.21.52-PM-1024x576.jpeg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-12-at-2.21.52-PM-300x169.jpeg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-12-at-2.21.52-PM-768x432.jpeg 768w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-12-at-2.21.52-PM.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, en las entradas y salidas directas a los sectores del mercado municipal, que convergen al Boulevard Central, por donde la mayor\u00eda que ingresa son habitantes de comunidades, no hab\u00eda en ninguna alguien aplicando gel antibacterial, ni tampoco se colocaron barandales met\u00e1licos para impedir el paso como en otras ocasiones.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-12-at-2.21.52-PM-2-1024x576.jpeg\" alt=\"\" class=\"wp-image-393174\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-12-at-2.21.52-PM-2-1024x576.jpeg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-12-at-2.21.52-PM-2-300x169.jpeg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-12-at-2.21.52-PM-2-768x432.jpeg 768w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-12-at-2.21.52-PM-2.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior, m\u00e1s que molestia gener\u00f3 temor y desconcierto en muchos habitantes de la cabecera municipal, en especial en mujeres madres de familia, quienes coincid\u00edan al expresar que el riesgo de la pandemia del COVID-19 est\u00e1 m\u00e1s latente, por lo que las autoridades no deben de &#8220;bajar la guardia&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quien responde al nombre de Mar\u00eda Rodr\u00edguez Hern\u00e1ndez, subray\u00f3 que los domingos en el tianguis y en el mercado municipal, hay una gran concentraci\u00f3n de personas, cuyo hacinamiento en los pasillos es una inminente fuente de contagios, por lo que el control en los accesos debe de ser muy estricto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Salvador Altamirano\/Zunoticia Huejutla, Hgo. &#8211; De acuerdo a la relaci\u00f3n de control en los filtros sanitizantes de accesos al tianguis y mercado municipal, compartida entre el Sector Salud, gremios de comerciantes y personal adscrito al municipio, este domingo le correspondi\u00f3 a los \u00faltimos, denot\u00e1ndose cierto descontrol en lo que respecta a su vital responsabilidad.&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/12\/descontrol-en-instalacion-de-filtros-sanitizantes-en-accesos-al-tianguis\/\">Seguir leyendo <span class=\"screen-reader-text\">Descontrol en instalaci\u00f3n de filtros sanitizantes en accesos al tianguis<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":393173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-393172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=393172"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393172\/revisions"}],"predecessor-version":[{"id":393176,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393172\/revisions\/393176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/393173"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=393172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=393172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=393172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}