{"id":393185,"date":"2021-09-12T14:57:46","date_gmt":"2021-09-12T19:57:46","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=393185"},"modified":"2021-09-12T14:57:47","modified_gmt":"2021-09-12T19:57:47","slug":"piden-despejar-calles-y-banquetas-obstruidas-en-parque-de-poblamiento","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/12\/piden-despejar-calles-y-banquetas-obstruidas-en-parque-de-poblamiento\/","title":{"rendered":"Piden despejar calles y banquetas obstruidas en Parque de Poblamiento"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">19<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F12%2Fpiden-despejar-calles-y-banquetas-obstruidas-en-parque-de-poblamiento%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/12\/piden-despejar-calles-y-banquetas-obstruidas-en-parque-de-poblamiento\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Francisco Rosas\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo. &#8211;<\/strong> La delegaci\u00f3n de la colonia Parque de Poblamiento y la direcci\u00f3n de Tr\u00e1nsito Municipal, piden a los vecinos de este sector poblacional para que despejen las calles y banquetas obstruidas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-12-at-2.21.52-PM-7.jpeg\" alt=\"\" class=\"wp-image-393187\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-12-at-2.21.52-PM-7.jpeg 720w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2021-09-12-at-2.21.52-PM-7-300x225.jpeg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad est\u00e1 siendo promovida por la mayor\u00eda de los colonos y este fin de semana las autoridades realizaron un recorrido en las diferentes calles para notificarles a los habitantes y retiren el material, cacharro, muebles, llantas, botellas, le\u00f1a, y carros chatarra que llevan a\u00f1os estacionados en un solo lugar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se dio a conocer que el departamento de tr\u00e1nsito lleva a cabo este proyecto que tiene como finalidad mantener la vialidad p\u00fablica y la seguridad de los habitantes de las colonias, adem\u00e1s de la presentaci\u00f3n y cultura, lo cual atraer\u00e1 muchas mejoras en las ventas, rentas, atractivo tur\u00edstico y todo un proyecto sustentable que en el futuro beneficiar\u00e1 a las generaciones m\u00e1s j\u00f3venes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo anterior, se exhorta a todos vecinos para que mantengan limpias las calles y banquetas de la colonia y respeten las \u00e1reas p\u00fablicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Francisco Rosas\/Zunoticia Huejutla, Hgo. &#8211; La delegaci\u00f3n de la colonia Parque de Poblamiento y la direcci\u00f3n de Tr\u00e1nsito Municipal, piden a los vecinos de este sector poblacional para que despejen las calles y banquetas obstruidas. La actividad est\u00e1 siendo promovida por la mayor\u00eda de los colonos y este fin de semana las autoridades realizaron&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/12\/piden-despejar-calles-y-banquetas-obstruidas-en-parque-de-poblamiento\/\">Seguir leyendo <span class=\"screen-reader-text\">Piden despejar calles y banquetas obstruidas en Parque de Poblamiento<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":393186,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[179,181],"tags":[121],"class_list":["post-393185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huasteca","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=393185"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393185\/revisions"}],"predecessor-version":[{"id":393188,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393185\/revisions\/393188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/393186"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=393185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=393185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=393185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}