{"id":393241,"date":"2021-09-12T19:43:12","date_gmt":"2021-09-13T00:43:12","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=393241"},"modified":"2021-09-12T19:43:13","modified_gmt":"2021-09-13T00:43:13","slug":"a-veces-se-gana-y-a-veces-se-aprende-victor-fernel","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/12\/a-veces-se-gana-y-a-veces-se-aprende-victor-fernel\/","title":{"rendered":"A veces se gana y a veces se aprende: V\u00edctor Fernel"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">80<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2021%2F09%2F12%2Fa-veces-se-gana-y-a-veces-se-aprende-victor-fernel%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/12\/a-veces-se-gana-y-a-veces-se-aprende-victor-fernel\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por \u00c1ngel Silverio\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>San Felipe Orizatl\u00e1n, Hgo. &#8211;<\/strong> V\u00edctor Fernel Guzm\u00e1n Arvizu, ex candidato a diputado local por el PRI, realiz\u00f3 una serie de recorridos por distintas localidades de los municipios que comprenden el distrito local tres, con el fin de agradecer el apoyo que recibi\u00f3 durante su campa\u00f1a, as\u00ed mismo dej\u00f3 en claro que seguir\u00e1 trabajando por el desarrollo de la regi\u00f3n desde su trinchera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entrevistado al respecto, Fernel Guzm\u00e1n, precis\u00f3, -\u201cUna de las cosas que siempre he querido es demostrarle a la gente que tenemos esa intenci\u00f3n de seguir apoyando, y ahora lo seguiremos haciendo desde la iniciativa privada, tal vez ya no tengo una responsabilidad formal, legal, pero no por eso vamos a dejar de trabajar y corresponderle a la gente que confi\u00f3 en nosotros, ya a partir de Xantolo, habremos de anunciar una serie de estrategias que estaremos impulsando para la regi\u00f3n, son cuatro acciones que vamos a emprender en ese \u00e1nimo de querer sumar y fortalecer y con ese objetivo que nos dejamos muy bien trazado que es el de preservar y promover el patrimonio cultural que representa en la sierra y la huasteca hidalguense\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que como muchas veces se gana y se aprende, &#8211; \u201cCreo que debemos saber a perder, y mi lema es a veces se gana y a veces se aprende, en esta ocasi\u00f3n nos toc\u00f3 aprender, pero cuando no se dan los resultados que uno espera, se genera un ejercicio de reflexi\u00f3n, de introspecci\u00f3n y es lo que hemos venido realizando, esta gira es para agradecer a las personas, y seguiremos haci\u00e9ndolo con mucho gusto\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guzm\u00e1n Arvizu, agreg\u00f3, &#8211; \u201cAntes de ser pol\u00edtico, somos seres humanos, y estamos comprometidos con la regi\u00f3n, obviamente yo voy a seguir sumando y apoyando a nuestras autoridades, a la gente, pues para realmente hacer congruencia en lo que en su momento fue un discurso de campa\u00f1a, y hoy tengo ese privilegio de mostrar la voluntad de poder aportar nuestro granito de arena en el desarrollo de nuestra regi\u00f3n\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por \u00c1ngel Silverio\/Zunoticia San Felipe Orizatl\u00e1n, Hgo. &#8211; V\u00edctor Fernel Guzm\u00e1n Arvizu, ex candidato a diputado local por el PRI, realiz\u00f3 una serie de recorridos por distintas localidades de los municipios que comprenden el distrito local tres, con el fin de agradecer el apoyo que recibi\u00f3 durante su campa\u00f1a, as\u00ed mismo dej\u00f3 en claro que&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2021\/09\/12\/a-veces-se-gana-y-a-veces-se-aprende-victor-fernel\/\">Seguir leyendo <span class=\"screen-reader-text\">A veces se gana y a veces se aprende: V\u00edctor Fernel<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":393242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[180],"tags":[129],"class_list":["post-393241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orizatlan","tag-orizatlan","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=393241"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393241\/revisions"}],"predecessor-version":[{"id":393243,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/393241\/revisions\/393243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/393242"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=393241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=393241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=393241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}