{"id":433326,"date":"2022-07-05T00:54:40","date_gmt":"2022-07-05T05:54:40","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=433326"},"modified":"2022-07-05T01:05:53","modified_gmt":"2022-07-05T06:05:53","slug":"dirigencia-seccional-que-encabezare-sera-de-tiempo-completo-said-vargas-saenz","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/dirigencia-seccional-que-encabezare-sera-de-tiempo-completo-said-vargas-saenz\/","title":{"rendered":"Dirigencia Seccional que encabezar\u00e9 ser\u00e1 de tiempo completo: Said Vargas S\u00e1enz"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">0<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2022%2F07%2F05%2Fdirigencia-seccional-que-encabezare-sera-de-tiempo-completo-said-vargas-saenz%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/dirigencia-seccional-que-encabezare-sera-de-tiempo-completo-said-vargas-saenz\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<ul class=\"wp-block-list\"><li>En su tercer d\u00eda, &#8220;Transformaci\u00f3n Sindical&#8221; recorre la regi\u00f3n del Altiplano, visitando a la base y llevando sus propuestas a sus centros de trabajo.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zempoala, Hgo.-<\/strong> Continuando con los trabajos rumbo a la conquista de la Secci\u00f3n 15 del Sindicato Nacional de Trabajadores de la Educaci\u00f3n, este lunes el Mtro. Said Vargas S\u00e1enz,&nbsp; acompa\u00f1ado de miembros de la Planilla Blanca que encabeza, recorrieron desde temprana hora distintos centros educativos en la regi\u00f3n del altiplano.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-12-28-14a.m..jpg\" alt=\"\" class=\"wp-image-433332\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-12-28-14a.m..jpg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-12-28-14a.m.-300x200.jpg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-12-28-14a.m.-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su recorrido que comenz\u00f3 en el municipio de Apan, pasando por Tepeapulco y concluyendo en Zempoala, se dieron cita distintos niveles educativos en varios planteles de la zona; esto con el fin de escuchar las propuestas de quien ya se postula como uno de los favoritos para dirigir al magisterio hidalguense, d\u00e1ndole acompa\u00f1amiento y arropo hacia su proyecto.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"697\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-12-28-31a.m..jpg\" alt=\"\" class=\"wp-image-433331\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-12-28-31a.m..jpg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-12-28-31a.m.-300x204.jpg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-12-28-31a.m.-768x523.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Con un di\u00e1logo abierto, y fuera de todo protocolo la base expres\u00f3 a Vargas S\u00e1enz su sentir ante el olvido que han sufrido en los \u00faltimos a\u00f1os, expresando la necesidad que tienen de una Dirigencia Sindical que atienda sus necesidades y demandas; por su parte el candidato de \u201cTransformaci\u00f3n Sindical\u201d dej\u00f3 bien claro que de ser beneficiado con el voto, su Directiva Seccional ser\u00e1 de puertas abiertas, buscando en todo momento atender de cerca a la base \u201cLa dirigencia seccional que encabezar\u00e9 no tendr\u00e1 horarios, ellos saben que no tendr\u00e1n fines de semana libres, pues trabajaremos de tiempo completo en favor de todas y todos los trabajadores de la educaci\u00f3n\u201d expres\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-12-28-49a.m..jpg\" alt=\"\" class=\"wp-image-433330\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-12-28-49a.m..jpg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-12-28-49a.m.-300x200.jpg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-12-28-49a.m.-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, habl\u00f3 de las propuestas que abanderan su campa\u00f1a, destacando que trabajar\u00e1 de la mano de quien guiar\u00e1 el destino de Hidalgo en el gobierno estatal, \u201cS\u00f3lo as\u00ed, con una pol\u00edtica sindical es como se logran las conquistas, no podemos estar peleados con el gobierno estatal\u201d se\u00f1al\u00f3 a los agremiados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte las y los maestros asistentes coincidieron en los puntos se\u00f1alados por el Mtro. Said Vargas reiterando el apoyo de sus centros de trabajo y compa\u00f1eros hacia el proyecto que abandera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En su tercer d\u00eda, &#8220;Transformaci\u00f3n Sindical&#8221; recorre la regi\u00f3n del Altiplano, visitando a la base y llevando sus propuestas a sus centros de trabajo. Por Redacci\u00f3n\/Zunoticia Zempoala, Hgo.- Continuando con los trabajos rumbo a la conquista de la Secci\u00f3n 15 del Sindicato Nacional de Trabajadores de la Educaci\u00f3n, este lunes el Mtro. Said Vargas S\u00e1enz,&nbsp;&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/dirigencia-seccional-que-encabezare-sera-de-tiempo-completo-said-vargas-saenz\/\">Seguir leyendo <span class=\"screen-reader-text\">Dirigencia Seccional que encabezar\u00e9 ser\u00e1 de tiempo completo: Said Vargas S\u00e1enz<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":433333,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-433326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=433326"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433326\/revisions"}],"predecessor-version":[{"id":433335,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433326\/revisions\/433335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/433333"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=433326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=433326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=433326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}