{"id":433365,"date":"2022-07-05T15:25:58","date_gmt":"2022-07-05T20:25:58","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=433365"},"modified":"2022-07-05T15:26:01","modified_gmt":"2022-07-05T20:26:01","slug":"comerciantes-del-mercado-consideran-masprioritaria-la-rehabilitacion-de-la-red-electrica","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/comerciantes-del-mercado-consideran-masprioritaria-la-rehabilitacion-de-la-red-electrica\/","title":{"rendered":"Comerciantes del mercado consideran m\u00e1s<br>prioritaria la rehabilitaci\u00f3n de la red el\u00e9ctrica"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">0<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2022%2F07%2F05%2Fcomerciantes-del-mercado-consideran-masprioritaria-la-rehabilitacion-de-la-red-electrica%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/comerciantes-del-mercado-consideran-masprioritaria-la-rehabilitacion-de-la-red-electrica\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Salvador Altamirano\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo.- <\/strong>Locatarios establecidos en el mercado municipal coinciden en se\u00f1alar que es m\u00e1s necesario y hasta urgente, el cambio total del cableado el\u00e9ctrico interno que el piso de uno o dos pasillos del inmueble, ya que por lo arcaico y mara\u00f1a de las l\u00edneas es latente que se suscite un incendio.<br>Por tal motivo, exhortan al dirigente de la Uni\u00f3n de Comerciantes Locatarios y Ambulantes (UCLA), Jorge Lara Garc\u00eda, \u201csi en verdad va a cristalizar la obra que pregona, rectifique y si quiere dejar un buen precedente que rehabilite la red el\u00e9ctrica, la cual por el deterioro y anarqu\u00eda que exhibe el mercado municipal est\u00e1 catalogada como bomba de tiempo&#8221;.<br>Agregaron que, la urgente rehabilitaci\u00f3n no necesariamente tiene que ser a cuenta o cargo de la UCLA, aunque hay para eso y m\u00e1s -acentuaron-, por lo que deben de dialogar con los propietarios de los locales para hacerlo de manera bipartita.<br>A pregunta formulada, reiteraron que es m\u00e1s urgente el cambio de cables que el piso, ya que nadie se ha ca\u00eddo en esos pasajes; en cambio de generarse un incendio quedar\u00edan sin patrimonio y empleos miles de personas, cuyas familias dependen del trabajo que se lleva a cabo en el mercado.<br>Para finalizar, criticaron la actitud que consideran mezquina y abusiva de los dirigentes de la UCLA, \u201centre ellos ex secretarios, ya que hay dinero de la organizaci\u00f3n en varias cuentas bancarias, que es de todos los socios y no solo de ellos, entonces por qu\u00e9 no emplearlo en algo tan necesario y urgente como el cambio del cableado\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Salvador Altamirano\/Zunoticia Huejutla, Hgo.- Locatarios establecidos en el mercado municipal coinciden en se\u00f1alar que es m\u00e1s necesario y hasta urgente, el cambio total del cableado el\u00e9ctrico interno que el piso de uno o dos pasillos del inmueble, ya que por lo arcaico y mara\u00f1a de las l\u00edneas es latente que se suscite un incendio.Por&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/comerciantes-del-mercado-consideran-masprioritaria-la-rehabilitacion-de-la-red-electrica\/\">Seguir leyendo <span class=\"screen-reader-text\">Comerciantes del mercado consideran m\u00e1s<br \/>prioritaria la rehabilitaci\u00f3n de la red el\u00e9ctrica<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":433366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-433365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=433365"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433365\/revisions"}],"predecessor-version":[{"id":433367,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433365\/revisions\/433367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/433366"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=433365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=433365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=433365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}