{"id":433385,"date":"2022-07-05T17:18:23","date_gmt":"2022-07-05T22:18:23","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=433385"},"modified":"2022-07-05T17:18:25","modified_gmt":"2022-07-05T22:18:25","slug":"se-desarrollan-las-clausuras-con-normalidad-y-medidas-preventivas","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/se-desarrollan-las-clausuras-con-normalidad-y-medidas-preventivas\/","title":{"rendered":"Se desarrollan las clausuras con normalidad y medidas preventivas"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">24<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2022%2F07%2F05%2Fse-desarrollan-las-clausuras-con-normalidad-y-medidas-preventivas%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/se-desarrollan-las-clausuras-con-normalidad-y-medidas-preventivas\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Roberto Meza\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo. &#8211;<\/strong> El supervisor de la zona cinco de los COBAEH en la huasteca, profesor Clemente Salazar Olivares, dijo que, las clausuras en diversas instituciones de este sistema educativo se desarrollan con toda normalidad y con los protocolos de bioseguridad; de esta forma sacar adelante las graduaciones de los alumnos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apunt\u00f3 que, hace unos d\u00edas iniciaron con el ciclo de clausuras en los municipios de Huejutla, Yahualica, San Felipe, Huazalingo y dem\u00e1s lugares; en donde muchos alumnos han concluido sus estudios y es una etapa feliz para ellos, por ello se llevan estos festejos como parte de su formaci\u00f3n acad\u00e9mica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ello agreg\u00f3, que durante los programas se establecen las medidas como es el uso de cubrebocas, el gel y la distancia adecuada de las personas; las clausuras est\u00e1n en una etapa media y a\u00fan falta varios COBAEH por hacer sus festejos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En estas acciones se felicita a todos los graduandos y a los padres de familia se les reconoce su tenacidad, esfuerzo y voluntad para sacar adelante a sus hijos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Roberto Meza\/Zunoticia Huejutla, Hgo. &#8211; El supervisor de la zona cinco de los COBAEH en la huasteca, profesor Clemente Salazar Olivares, dijo que, las clausuras en diversas instituciones de este sistema educativo se desarrollan con toda normalidad y con los protocolos de bioseguridad; de esta forma sacar adelante las graduaciones de los alumnos. Apunt\u00f3&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/se-desarrollan-las-clausuras-con-normalidad-y-medidas-preventivas\/\">Seguir leyendo <span class=\"screen-reader-text\">Se desarrollan las clausuras con normalidad y medidas preventivas<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":433386,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-433385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=433385"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433385\/revisions"}],"predecessor-version":[{"id":433387,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433385\/revisions\/433387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/433386"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=433385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=433385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=433385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}