{"id":433413,"date":"2022-07-05T19:10:22","date_gmt":"2022-07-06T00:10:22","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=433413"},"modified":"2022-07-05T19:10:23","modified_gmt":"2022-07-06T00:10:23","slug":"julio-menchaca-pospone-gira-de-agradecimiento-por-contagios-de-covid","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/julio-menchaca-pospone-gira-de-agradecimiento-por-contagios-de-covid\/","title":{"rendered":"Julio Menchaca pospone gira de agradecimiento por contagios de Covid"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">18<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2022%2F07%2F05%2Fjulio-menchaca-pospone-gira-de-agradecimiento-por-contagios-de-covid%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/julio-menchaca-pospone-gira-de-agradecimiento-por-contagios-de-covid\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pachuca, Hgo.-<\/strong> Julio Menchaca Salazar, gobernador electo del estado de Hidalgo, dio a conocer que pospondr\u00e1 su gira de agradecimiento por los diferentes distritos electorales debido al incremento de casos de covid 19 en territorio hidalguense, a fin de salvaguardar la integridad de la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior debido al alza en la cifra de contagios que se ha registrado en gran parte del territorio estatal, sobre todo en 11 municipios, donde incluso 79 escuelas cerraron actividades para cuidar la salud de las y los estudiantes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-07-05-44p.m.-1024x682.jpg\" alt=\"\" class=\"wp-image-433416\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-07-05-44p.m.-1024x682.jpg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-07-05-44p.m.-300x200.jpg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-07-05-44p.m.-768x512.jpg 768w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-07-05-44p.m..jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Menchaca Salazar lament\u00f3 tener que posponer esta gira, pero consider\u00f3 importante poner en primer lugar la salud de las y los hidalguenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPor ahora lo importante es que nos mantengamos seguras y seguros. Ya pr\u00f3ximamente, cuando las autoridades de salud informen que disminuye la curva de contagios, tendremos la oportunidad de volver a saludarnos\u201d, recalc\u00f3 el gobernador electo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-07-03-12p.m.-1024x682.jpg\" alt=\"\" class=\"wp-image-433418\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-07-03-12p.m.-1024x682.jpg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-07-03-12p.m.-300x200.jpg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-07-03-12p.m.-768x512.jpg 768w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/eZy-Watermark-05-07-2022-07-03-12p.m..jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, Menchaca hizo un llamado a la poblaci\u00f3n para que se mantenga alerta ante la contingencia sanitaria y a mantener los protocolos de prevenci\u00f3n, para que la curva de contagios vaya a la baja, adem\u00e1s de estar al tanto de los avisos de la Secretar\u00eda de Salud de Hidalgo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Pachuca, Hgo.- Julio Menchaca Salazar, gobernador electo del estado de Hidalgo, dio a conocer que pospondr\u00e1 su gira de agradecimiento por los diferentes distritos electorales debido al incremento de casos de covid 19 en territorio hidalguense, a fin de salvaguardar la integridad de la ciudadan\u00eda. Lo anterior debido al alza en la cifra&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/julio-menchaca-pospone-gira-de-agradecimiento-por-contagios-de-covid\/\">Seguir leyendo <span class=\"screen-reader-text\">Julio Menchaca pospone gira de agradecimiento por contagios de Covid<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":433417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-433413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=433413"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433413\/revisions"}],"predecessor-version":[{"id":433425,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433413\/revisions\/433425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/433417"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=433413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=433413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=433413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}