{"id":433485,"date":"2022-07-05T22:01:32","date_gmt":"2022-07-06T03:01:32","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=433485"},"modified":"2022-07-05T22:01:33","modified_gmt":"2022-07-06T03:01:33","slug":"debe-haber-inclusion-de-indigenas-en-el-proximo-gobierno-estatal","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/debe-haber-inclusion-de-indigenas-en-el-proximo-gobierno-estatal\/","title":{"rendered":"Debe haber inclusi\u00f3n de ind\u00edgenas en el pr\u00f3ximo gobierno estatal"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">8<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2022%2F07%2F05%2Fdebe-haber-inclusion-de-indigenas-en-el-proximo-gobierno-estatal%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/debe-haber-inclusion-de-indigenas-en-el-proximo-gobierno-estatal\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por \u00c1ngel Silverio\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>San Felipe Orizatl\u00e1n, Hgo.-<\/strong> &#8220;En nuestra regi\u00f3n y en todo nuestro estado, hay ind\u00edgenas muy bien preparados acad\u00e9micamente, creo que si hoy se quiere dar muestra de un cambio, este gobierno pr\u00f3ximo debe incluir a nuestros hermanos ind\u00edgenas, capaces de hacer mucho por su tierra, as\u00ed como las comunidades ind\u00edgenas&nbsp; confiaron en el proyecto de Julio Menchaca, creo que se le debe dar la oportunidad de que formen parte de su gabinete&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo mencion\u00f3 Justino Hern\u00e1ndez Amador, al cuestionarle sobre el pr\u00f3ximo gobierno y los perfiles que esperan del gabinete del gobernador electo, Julio Menchaca, reiterando que debe haber inclusi\u00f3n de ind\u00edgenas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Tenemos mucho talento en nuestras comunidades, ya no es como antes, hoy nuestra gente ha salido y se ha preparado con estudios profesionales, algunos con maestr\u00edas, doctorados, posgrados, y m\u00e1s, en toda la regi\u00f3n hay gente muy preparada que bien puede ocupar un espacio como una Secretar\u00eda, ojal\u00e1 que este gobierno tome en cuenta a nuestros hermanos ind\u00edgenas&#8221; indic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00f1adi\u00f3 que, desde la gubernatura ind\u00edgena, estar\u00e1n haciendo la gesti\u00f3n para que el pr\u00f3ximo gobernador tome en cuenta est\u00e1 solicitud, aunque mencion\u00f3, -&#8220;Creo que no es necesario la gesti\u00f3n, \u00e9l tiene el compromiso con las comunidades ind\u00edgenas, esperamos que se cumpla y que sean integrados en su gabinete&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por \u00c1ngel Silverio\/Zunoticia San Felipe Orizatl\u00e1n, Hgo.- &#8220;En nuestra regi\u00f3n y en todo nuestro estado, hay ind\u00edgenas muy bien preparados acad\u00e9micamente, creo que si hoy se quiere dar muestra de un cambio, este gobierno pr\u00f3ximo debe incluir a nuestros hermanos ind\u00edgenas, capaces de hacer mucho por su tierra, as\u00ed como las comunidades ind\u00edgenas&nbsp; confiaron en&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/05\/debe-haber-inclusion-de-indigenas-en-el-proximo-gobierno-estatal\/\">Seguir leyendo <span class=\"screen-reader-text\">Debe haber inclusi\u00f3n de ind\u00edgenas en el pr\u00f3ximo gobierno estatal<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":433462,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[180],"tags":[129],"class_list":["post-433485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orizatlan","tag-orizatlan","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=433485"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433485\/revisions"}],"predecessor-version":[{"id":433486,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433485\/revisions\/433486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/433462"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=433485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=433485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=433485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}