{"id":433512,"date":"2022-07-06T15:07:36","date_gmt":"2022-07-06T20:07:36","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=433512"},"modified":"2022-07-06T21:54:51","modified_gmt":"2022-07-07T02:54:51","slug":"enjambre-de-abejas-ataca-a-ninos-en-escuela-primaria","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/06\/enjambre-de-abejas-ataca-a-ninos-en-escuela-primaria\/","title":{"rendered":"23 ni\u00f1os lesionados por enjambre de abejas"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">19<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2022%2F07%2F06%2Fenjambre-de-abejas-ataca-a-ninos-en-escuela-primaria%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/06\/enjambre-de-abejas-ataca-a-ninos-en-escuela-primaria\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Pedro Luciano\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tlanchinol, Hgo. &#8211;<\/strong> Los hechos acontecieron aproximadamente a las 11:00 horas de este mi\u00e9rcoles, cuando un enjambre de abejas se ubic\u00f3 dentro de las instalaciones de la primaria \u201cJusto Sierra\u201d, de la cabecera municipal de Tlanchinol; en donde por curiosidad de los ni\u00f1os, \u00e9stas fueron molestadas, provocando que dicho enjambre se tornara agresivo, lo cual provoc\u00f3 el ataque a estudiantes y maestros dejando un saldo de 23 ni\u00f1os lesionados con m\u00faltiples picaduras, as\u00ed como tres docentes y muchos m\u00e1s con crisis nerviosa, siendo trasladados al Hospital Ilusi\u00f3n para su valoraci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.52-PM-2-768x1024.jpeg\" alt=\"\" class=\"wp-image-433515\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.52-PM-2-768x1024.jpeg 768w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.52-PM-2-225x300.jpeg 225w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.52-PM-2.jpeg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Refiri\u00f3 el director del \u00e1rea de Protecci\u00f3n Civil de Tlanchinol, que esperaban la valoraci\u00f3n de los especialistas en salud para descartar lesiones de gravedad en los menores de edad afectados tras este incidente, dentro de la escuela primaria; por lo cual hasta el momento se contabilizan 23 ni\u00f1os y tres maestras con picaduras m\u00faltiples.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.55-PM-1024x682.jpeg\" alt=\"\" class=\"wp-image-433525\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.55-PM-1024x682.jpeg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.55-PM-300x200.jpeg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.55-PM-768x512.jpeg 768w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.55-PM.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">De igual forma, refiri\u00f3 que al lugar se present\u00f3 personal perteneciente al \u00e1rea de Protecci\u00f3n Civil, as\u00ed como miembros rescatistas del grupo Halcones Tlanchinol, una ambulancia del ayuntamiento y elementos de Seguridad P\u00fablica con la finalidad de auxiliar en las tareas de control de enjambres utilizando el equipo id\u00f3neo para hacer frente a dichos animales, concretar su captura oportuna y en su momento reubicarlos en los espacios naturales para que estos sean liberados y no se corra el riesgo de futuros ataques a la poblaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"767\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.52-PM-4-1024x767.jpeg\" alt=\"\" class=\"wp-image-433514\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.52-PM-4-1024x767.jpeg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.52-PM-4-300x225.jpeg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.52-PM-4-768x575.jpeg 768w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-06-at-3.03.52-PM-4.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe mencionar que, como medida preventiva se desaloj\u00f3 a todo el personal docente, administrativo, alumnos y las clases fueron suspendidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Concluy\u00f3 refiriendo que, es indispensable que se levanten los reportes y se comunique a las autoridades competentes ya sea Protecci\u00f3n Civil o Seguridad P\u00fablica, en caso de observar la presencia de dichos animales en \u00e1reas urbanas y a\u00fan m\u00e1s en instituciones educativas; lo anterior para que se ejecuten las acciones necesarias y evitar ataques a la poblaci\u00f3n en general.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Pedro Luciano\/Zunoticia Tlanchinol, Hgo. &#8211; Los hechos acontecieron aproximadamente a las 11:00 horas de este mi\u00e9rcoles, cuando un enjambre de abejas se ubic\u00f3 dentro de las instalaciones de la primaria \u201cJusto Sierra\u201d, de la cabecera municipal de Tlanchinol; en donde por curiosidad de los ni\u00f1os, \u00e9stas fueron molestadas, provocando que dicho enjambre se tornara&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/06\/enjambre-de-abejas-ataca-a-ninos-en-escuela-primaria\/\">Seguir leyendo <span class=\"screen-reader-text\">23 ni\u00f1os lesionados por enjambre de abejas<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":433513,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[219,201],"tags":[127],"class_list":["post-433512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sierra","category-tlanchinol","tag-tlanchinol","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=433512"}],"version-history":[{"count":3,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433512\/revisions"}],"predecessor-version":[{"id":433622,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433512\/revisions\/433622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/433513"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=433512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=433512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=433512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}