{"id":433611,"date":"2022-07-06T19:56:49","date_gmt":"2022-07-07T00:56:49","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=433611"},"modified":"2022-07-06T19:56:50","modified_gmt":"2022-07-07T00:56:50","slug":"remuneracion-justa-a-un-trabajo-justo-luna-mejia","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/06\/remuneracion-justa-a-un-trabajo-justo-luna-mejia\/","title":{"rendered":"\u201cRemuneraci\u00f3n justa a un trabajo justo\u201d: Luna Mej\u00eda"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">33<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2022%2F07%2F06%2Fremuneracion-justa-a-un-trabajo-justo-luna-mejia%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/06\/remuneracion-justa-a-un-trabajo-justo-luna-mejia\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Agua Blanca, Hgo.-<\/strong> Juan Jos\u00e9 Luna Mej\u00eda, candidato a Secretario General de la Secci\u00f3n 15 del SNTE, recorri\u00f3 este mi\u00e9rcoles los municipios de Agua Blanca y Metepec, en busca de que los trabajadores de la educaci\u00f3n agremiados escuchen las propuestas de la planilla Azul PreSNTE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El maestro Juan Jos\u00e9 Luna escuch\u00f3 las preocupaciones de los sindicalizados, quienes mostraron su inquietud acerca de la manera en la que se asignan las horas, lo resulta en una remuneraci\u00f3n que no corresponde con las horas trabajadas. En este sentido, Luna comparti\u00f3 con ellos su propuesta de regularizar esta situaci\u00f3n en Secundarias Generales, T\u00e9cnicas, Telesecundarias, as\u00ed como Educaci\u00f3n F\u00edsica, y es que, dijo, \u201c<strong>los trabajadores est\u00e1n perdiendo dinero<\/strong> al no calcularse debidamente sus prestaciones, su aguinaldo, primas vacacionales, adem\u00e1s de lamentables situaciones de pagos intermitentes, algo que se ha dejado crecer, como bola de nieve\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un ejemplo de ello son las claves de escuelas Normales, acot\u00f3, las cuales son bien cotizadas, y bien pagadas, porque requieren cierto nivel de preparaci\u00f3n, sin embargo, estas claves <strong>son ostentadas por funcionarios de la Secretar\u00eda de Educaci\u00f3n P\u00fablica, por funcionarios de Secci\u00f3n, y<\/strong> \u201c<strong>los maestros que s\u00ed trabajan en Normales ostentan claves de Primaria General, Telesecundaria, de una prefectura\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los maestros que s\u00ed trabajan en Normales, deben tener una clave correspondiente a ese subsistema.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es as\u00ed que <strong>Luna Mej\u00eda propone un sistema de horas que encuadre en la legislaci\u00f3n laboral y reglamentaria, de modo que se les remunere a los trabajadores de manera, correcta, justa<\/strong> seg\u00fan el trabajo que realicen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSiempre hay una soluci\u00f3n a una justa demanda\u201d, y es que, dijo, hay compa\u00f1eros que tienen hasta 30 a\u00f1os o m\u00e1s en esta situaci\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs una deuda hist\u00f3rica con el <strong>personal de Apoyo, intendentes y personal administrativo<\/strong>, que no ganan mucho, pero que, <strong>con base en su esfuerzo, actualizaci\u00f3n, cursos de capacitaci\u00f3n<\/strong>, otro ejemplo, les dan un est\u00edmulo quincenal, <strong>mismo que, al momento de su jubilaci\u00f3n no es considerado en el c\u00e1lculo de su pensi\u00f3n<\/strong>. \u201cPor situaciones como esta, <strong>tenemos que hacer que se integre este est\u00edmulo de carrera administrativa para que se goce de una pensi\u00f3n digna<\/strong>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el nivel de educaci\u00f3n Especial, Juan Jos\u00e9 Luna <strong>propone que las claves sean exclusivas<\/strong>, ya que los compa\u00f1eros laboran 25 horas y sus claves equivalen a 20 horas, y eso contradice a lo dicho por el hoy presidente de la Rep\u00fablica, que es un salario justo para un trabajo justo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tenemos la voluntad de sacar adelante estos proyectos para hacer justicia a nuestras bases. \u201cEs lo justo\u201d, remat\u00f3<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Agua Blanca, Hgo.- Juan Jos\u00e9 Luna Mej\u00eda, candidato a Secretario General de la Secci\u00f3n 15 del SNTE, recorri\u00f3 este mi\u00e9rcoles los municipios de Agua Blanca y Metepec, en busca de que los trabajadores de la educaci\u00f3n agremiados escuchen las propuestas de la planilla Azul PreSNTE. El maestro Juan Jos\u00e9 Luna escuch\u00f3 las preocupaciones&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/06\/remuneracion-justa-a-un-trabajo-justo-luna-mejia\/\">Seguir leyendo <span class=\"screen-reader-text\">\u201cRemuneraci\u00f3n justa a un trabajo justo\u201d: Luna Mej\u00eda<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":433604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-433611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=433611"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433611\/revisions"}],"predecessor-version":[{"id":433612,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433611\/revisions\/433612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/433604"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=433611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=433611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=433611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}