{"id":433800,"date":"2022-07-07T23:33:22","date_gmt":"2022-07-08T04:33:22","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=433800"},"modified":"2022-07-08T00:18:13","modified_gmt":"2022-07-08T05:18:13","slug":"espejeando-por-perseo-341","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/07\/espejeando-por-perseo-341\/","title":{"rendered":"ESPEJEANDO por Perseo"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">9<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2022%2F07%2F07%2Fespejeando-por-perseo-341%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/07\/espejeando-por-perseo-341\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\">\u2022 El secretario de salud Alejandro Efra\u00edn Ben\u00edtez Herrera sigue con una campa\u00f1a de recomendaciones contra el tema de los contagios, tema que sin duda, por la importancia y trascendencia estar\u00e1 siendo compartida esta responsabilidad con quien ser\u00e1 el pr\u00f3ximo secretario de salud con Julio Menchaca para hilar algo tan delicado para cualquier gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Si bien una cosa es la entrega recepci\u00f3n del gobierno, hay rubros delicados como Salud, Educaci\u00f3n y Seguridad que deben llegar perfilados para continuar con una tarea cuya eficacia depende de la atenci\u00f3n continua, permanente y s\u00f3lida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Independientemente de las mejoras, las innovaciones o pol\u00edticas p\u00fablicas a implementar en estos rubros, la delicadeza de estos tres rubros no tiene igual, incluso deber\u00eda incluirse Protecci\u00f3n Civil por que estamos en Temporada de huracanes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Los contagios de las variantes de COVID y su atenci\u00f3n, la seguridad p\u00fablica y la estrategia de protecci\u00f3n civil deben llegar finitos a sus \u00e1reas en el siguiente gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Lo anterior nada tiene que ver con poder u otra circunstancia, sino por que todo incide en la integridad de los ciudadanos, los rubros arriba descritos son ejes centrales de cualquier gobierno y tambi\u00e9n &#8220;El Tal\u00f3n de Aquiles&#8221;. La coordinaci\u00f3n en la continuidad de la atenci\u00f3n ciudadana y la delicadeza de los rubros amerita que estas \u00e1reas sigan siendo parte de una objetiva visi\u00f3n y consideraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u2022 La planilla Naranja se desinfla y no despega. A\u00fan pintando los edificios de Naranja, usando la estructura oficial, la presi\u00f3n, la mentira y el uso faccioso de los recursos de las cuotas de los trabajadores, la base magisterial ya les dio la vuelta, ya no quieren m\u00e1s de lo mismo y la base comienza a democratizar la ruta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u2022 El intento de la planilla Naranja tiene que ver con las viejas pr\u00e1cticas que la gente ya entendi\u00f3, que no funcionan en este momento, sobre todo ante un escenario del docente que sabe que la llave para hacer las cosas bien est\u00e1 de su lado, les toca decidir a ellos y todo indica que el mensaje ser\u00e1 contundente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u2022 Luis Enrique Morales Acosta comienza a ver nubarrones en el intento de pasar la estafeta a sus corifeos y no tarda en darles la espalda y comenzar a buscar de d\u00f3nde sujetarse porque pudiera quedar en medio de la marea alta y el arrecife y llegar a esa hora del atardecer sin salvavidas pudiera llevarlo a consecuencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u2022 Ayer Juan Jos\u00e9 Luna Mej\u00eda de pasadita se refiri\u00f3 a que de ganar implementar\u00e1 auditor\u00edas en todos los rubros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u2022\u2022 El que anda sumando adeptos en sierra y huasteca es el profesor Said Vargas S\u00e1enz, candidato de la planilla blanca, quien tambi\u00e9n arriba a la huasteca llevando consigo propuestas para la base magisterial que han generado la atracci\u00f3n del maestro com\u00fan, que son los que mandan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u2022\u2022 Said Vargas parece ha dimensionado el valor de la base magisterial y el poder que la democracia sindical les ha otorgado, adem\u00e1s se aprecia dispuesto a entender este mandato de la base, sabe que de tomar la responsabilidad tendr\u00e1 que ser un dirigente que obedecer\u00e1 la nueva instrucci\u00f3n de la democracia, mandar obedeciendo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"657\" height=\"776\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-08-at-12.15.45-AM.jpeg\" alt=\"\" class=\"wp-image-433803\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-08-at-12.15.45-AM.jpeg 657w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-08-at-12.15.45-AM-254x300.jpeg 254w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 El secretario de salud Alejandro Efra\u00edn Ben\u00edtez Herrera sigue con una campa\u00f1a de recomendaciones contra el tema de los contagios, tema que sin duda, por la importancia y trascendencia estar\u00e1 siendo compartida esta responsabilidad con quien ser\u00e1 el pr\u00f3ximo secretario de salud con Julio Menchaca para hilar algo tan delicado para cualquier gobierno. \u2022&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/07\/espejeando-por-perseo-341\/\">Seguir leyendo <span class=\"screen-reader-text\">ESPEJEANDO por Perseo<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":433801,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[176],"tags":[205],"class_list":["post-433800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espejeando","tag-espejeando","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=433800"}],"version-history":[{"count":2,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433800\/revisions"}],"predecessor-version":[{"id":433804,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/433800\/revisions\/433804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/433801"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=433800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=433800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=433800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}