{"id":434020,"date":"2022-07-09T21:39:01","date_gmt":"2022-07-10T02:39:01","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=434020"},"modified":"2022-07-09T21:39:04","modified_gmt":"2022-07-10T02:39:04","slug":"golpeado-aparece-delegado-de-la-corrala","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/09\/golpeado-aparece-delegado-de-la-corrala\/","title":{"rendered":"Golpeado, aparece delegado de la Corrala"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">23<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2022%2F07%2F09%2Fgolpeado-aparece-delegado-de-la-corrala%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/09\/golpeado-aparece-delegado-de-la-corrala\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo.-<\/strong> Con varias lesiones en su humanidad fue localizada una persona del sexo masculino en un camino de terracer\u00eda, se trata del delegado de la comunidad de La Corrala, que desde hace varios d\u00edas se encontraba en calidad de desaparecido tras ser presuntamente secuestrado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los hechos ocurrieron durante el transcurso de la tarde del s\u00e1bado sobre el camino de terracer\u00eda que conduce a la Localidad de La Corrala perteneciente a Huejutla, cerca de la comunidad de Huichapa, Jaltoc\u00e1n, cuando elementos de Seguridad P\u00fablica Estatal fueron movilizados ante el reporte de peatones que mencionaban que una persona del sexo masculino hab\u00eda sido localizada en esa zona con varios golpes en su humanidad y que refer\u00eda presuntamente haber sido abandonada tras encontrarse secuestrado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-09-at-9.26.21-PM-1024x768.jpeg\" alt=\"\" class=\"wp-image-434021\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-09-at-9.26.21-PM-1024x768.jpeg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-09-at-9.26.21-PM-300x225.jpeg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-09-at-9.26.21-PM-768x576.jpeg 768w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-09-at-9.26.21-PM.jpeg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed mismo, inmediatamente los cuerpos de emergencia se trasladaron hasta el sitio, donde elementos del cuerpo de bomberos le brindaron la atenci\u00f3n al hombre que se identific\u00f3 como Hermenegildo Grande Hern\u00e1ndez, quien era delegado de la comunidad de La Corrala y que desde hace aproximadamente una semana se encontraba en calidad de desaparecido, de igual forma se mencionaba que el delegado hab\u00eda sido secuestrado y que sus captores exig\u00edan la cantidad de 150 mil pesos para su liberaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pese a lo anterior, en d\u00edas pasados habitantes de La Corrala llevaron a cabo una reuni\u00f3n donde acordaron multar a su autoridad con 50 mil pesos en caso de volver a aparecer, ya que cre\u00edan que se trataba de un auto secuestro, debido a que el hombre presuntamente hab\u00eda robado el sello de la localidad, dinero en efectivo de la caja y las llaves de la delegaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-09-at-9.26.20-PM-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-434022\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-09-at-9.26.20-PM-1-1024x768.jpeg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-09-at-9.26.20-PM-1-300x225.jpeg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-09-at-9.26.20-PM-1-768x576.jpeg 768w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-09-at-9.26.20-PM-1.jpeg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">De igual forma, los molestos vecinos optaron por cambiar de delegado para quedar a cargo quien se identific\u00f3 como Esteban Franco Hern\u00e1ndez, sin embargo, ser\u00e1n las autoridades polic\u00edacas quienes se encarguen de realizar las investigaciones correspondientes para esclarecer los hechos, mientras tanto la v\u00edctima de presunto secuestro fue canalizada a una cl\u00ednica para recibir atenci\u00f3n m\u00e9dica, por lo que se espera que ante su recuperaci\u00f3n declare ante el ministerio p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Huejutla, Hgo.- Con varias lesiones en su humanidad fue localizada una persona del sexo masculino en un camino de terracer\u00eda, se trata del delegado de la comunidad de La Corrala, que desde hace varios d\u00edas se encontraba en calidad de desaparecido tras ser presuntamente secuestrado. Los hechos ocurrieron durante el transcurso de la&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/09\/golpeado-aparece-delegado-de-la-corrala\/\">Seguir leyendo <span class=\"screen-reader-text\">Golpeado, aparece delegado de la Corrala<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":434023,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[178,209],"tags":[121,259],"class_list":["post-434020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiaca","category-relevante","tag-huejutla","tag-policiaca","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/434020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=434020"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/434020\/revisions"}],"predecessor-version":[{"id":434024,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/434020\/revisions\/434024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/434023"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=434020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=434020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=434020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}