{"id":434152,"date":"2022-07-11T00:33:28","date_gmt":"2022-07-11T05:33:28","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=434152"},"modified":"2022-07-11T00:33:32","modified_gmt":"2022-07-11T05:33:32","slug":"espejeando-por-perseo-344","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/11\/espejeando-por-perseo-344\/","title":{"rendered":"Espejeando Por Perseo"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">5<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2022%2F07%2F11%2Fespejeando-por-perseo-344%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/11\/espejeando-por-perseo-344\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\">\u2022 En la huasteca y sierra, los municipios azules como Tlanchinol y Xochiatipan, las figuras que se perfilan, o que cuando menos han hecho ruido, para buscar mantener los municipios del mismo color, son Manolo Guti\u00e9rrez por Xochiatipan y Gabino Hern\u00e1ndez Vite por Tlanchinol; aunque en este \u00faltimo municipio habr\u00e1 que ver la postura de otros grupos pol\u00edticos afines entre s\u00ed, que conjuntados han gobernado casi durante los \u00faltimos 20 a\u00f1os; y ahora estos personajes se la van a jugar seguramente con todo lo que tienen y llevan con tiempo su proyecto buscando adelantar l\u00edneas para no errarle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 En Xochiatipan, habr\u00e1 que ver, igualmente, si los esc\u00e1ndalos protagonizados por quien fuera presidente municipal no le merman posibilidades. Lo que le vale sin duda es que el actual presidente municipal est\u00e1 haciendo un buen trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 En Tlanchinol el PRI jug\u00f3 del lado de Morena y es obvio que los intereses mostraron su lado de efecto, logrando sacar la elecci\u00f3n en votos para Julio Menchaca y con ello marcar la ruta electoral, que ya es brecha pol\u00edtica contra lo que tienen que luchar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 En Xochiatipan recordar\u00e1n que, en el proceso electoral pasado, una apreciaci\u00f3n que se percibi\u00f3 fue que los del PRI se fueron a la cargada hacia el PAN para lograr ganar holgados, sin embargo, en la lectura a gobernador conjuntar los intereses y orientar a un solo objetivo les dio n\u00fameros nunca vistos, es decir, estos mismos intereses con un proyecto municipal bien encabezado pues pudieran remontar locamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Recordemos que cuando se trata de proyectos municipales los rompimientos se incrementan por que muchos intereses participan en las partes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u2022 El PRI en la huasteca tiene un desaf\u00edo muy marcado porque los intereses en la gubernatura cambian cuando se trata de la municipal, los intereses que no se concilian en Morena repercutir\u00e1n en la utilidad del tricolor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u2022 Morena tendr\u00e1 la mayor de la responsabilidad por tener candidatos ciudadanos que satisfagan la exigencia de la base pol\u00edtica, entre los denominados de izquierda, los lopezobradoristas y los neomorenistas, eso ser\u00e1 todo un reto porque no todos se someten a las decisiones centralistas en las que luego confunden a las bases con palabras y aspectos dif\u00edciles de digerir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u2022\u2022 Por otro lado tenemos a los liderazgos naturales que no necesitan o est\u00e1n esperanzados a las siglas del momento para levantar \u00e1mpula. Siempre hay figuras naturales que marcan diferencias, que son quiz\u00e1s cuestionables, pol\u00e9micas entre los actores pol\u00edticos, pero con resultados positivos con la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u2022\u2022 Hoy el escenario que tenemos a un a\u00f1o m\u00e1ximo por los Ayuntamientos, que representan el aderezo social por ser los m\u00e1s cercanos a la poblaci\u00f3n de comunidades, colonias, barrios y sectores populares. De estos personajes dependen los abanderados a diputados locales, federales y los pr\u00f3ximos Senadores por Hidalgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u2022\u2022 La realidad pol\u00edtica la veremos en el 2024, primero porque el gran elector social se hizo con Andr\u00e9s Manuel L\u00f3pez Obrador, sin dejar de observar que el Presidente de M\u00e9xico no ir\u00e1 en alg\u00fan cargo p\u00fablico- seg\u00fan sus palabras- terminando se ir\u00eda a su rancho La Chingada en Tabasco; entendamos el nuevo momento de Morena sin AMLO en la boleta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u2022\u2022\u2022 Comenz\u00f3 a aparecer el Senador Ricardo Monreal \u00c1vila en los promocionales de su figura pol\u00edtica, que sin duda al no ser el &#8220;oficial&#8221; o la corcholata pol\u00edtica del poder pol\u00edtico, le han llovido cr\u00edticas, pero externamente de Morena ha acaparado de afuera hacia adentro los apoyos ciudadanos y eso le da mayores posibilidades de ser el pr\u00f3ximo abanderado pol\u00edtico a la presidencia de la rep\u00fablica,&nbsp; con legitimidad social que les va a crecer al Interior de Morena\u2026 o de alg\u00fan otro proyecto pol\u00edtico, ciudadano o independiente. Por que lo que si se aprecia es su postura echada pa\u2019 delante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 En la huasteca y sierra, los municipios azules como Tlanchinol y Xochiatipan, las figuras que se perfilan, o que cuando menos han hecho ruido, para buscar mantener los municipios del mismo color, son Manolo Guti\u00e9rrez por Xochiatipan y Gabino Hern\u00e1ndez Vite por Tlanchinol; aunque en este \u00faltimo municipio habr\u00e1 que ver la postura de&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/11\/espejeando-por-perseo-344\/\">Seguir leyendo <span class=\"screen-reader-text\">Espejeando Por Perseo<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":434155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[176],"tags":[205],"class_list":["post-434152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espejeando","tag-espejeando","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/434152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=434152"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/434152\/revisions"}],"predecessor-version":[{"id":434156,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/434152\/revisions\/434156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/434155"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=434152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=434152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=434152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}