{"id":434256,"date":"2022-07-11T19:53:59","date_gmt":"2022-07-12T00:53:59","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=434256"},"modified":"2022-07-11T19:54:01","modified_gmt":"2022-07-12T00:54:01","slug":"comerciantes-siguen-tirando-basura-a-un-costado-del-puente-la-tolva","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/11\/comerciantes-siguen-tirando-basura-a-un-costado-del-puente-la-tolva\/","title":{"rendered":"Comerciantes siguen tirando basura a un costado del puente La Tolva"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">23<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2022%2F07%2F11%2Fcomerciantes-siguen-tirando-basura-a-un-costado-del-puente-la-tolva%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/11\/comerciantes-siguen-tirando-basura-a-un-costado-del-puente-la-tolva\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Francisco Rosas\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo.-<\/strong> Comerciantes del mercado municipal de esta ciudad contin\u00faan tirando basura a un costado del puente La Tolva, ubicado en la calle Constituyentes de la colonia Los Cantores, lo cual representa un foco de contaminaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Familias que viven en este sector poblacional indicaron que las autoridades municipales prohibieron tirar desechos s\u00f3lidos en el lugar, ya que todos los d\u00edas hab\u00eda una pestilencia insoportable, por lo que designaron otros puntos para la recolecci\u00f3n de la basura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, esta disposici\u00f3n solo fue respetada unos d\u00edas por los mercaderes y actualmente hay montones de basura en v\u00eda p\u00fablica, esto aprovechando que ya no hay vigilancia polic\u00edaca en la zona, afirm\u00f3 Jaime Santos Hern\u00e1ndez, vecino de esta colonia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El quejoso, coment\u00f3 que es necesario que las autoridades municipales apliquen sanciones a los comerciantes que sigan tirando basura a un costado del puente La Tolva, enfatiz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Francisco Rosas\/Zunoticia Huejutla, Hgo.- Comerciantes del mercado municipal de esta ciudad contin\u00faan tirando basura a un costado del puente La Tolva, ubicado en la calle Constituyentes de la colonia Los Cantores, lo cual representa un foco de contaminaci\u00f3n. Familias que viven en este sector poblacional indicaron que las autoridades municipales prohibieron tirar desechos s\u00f3lidos&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/11\/comerciantes-siguen-tirando-basura-a-un-costado-del-puente-la-tolva\/\">Seguir leyendo <span class=\"screen-reader-text\">Comerciantes siguen tirando basura a un costado del puente La Tolva<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":434244,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-434256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/434256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=434256"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/434256\/revisions"}],"predecessor-version":[{"id":434257,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/434256\/revisions\/434257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/434244"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=434256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=434256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=434256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}