{"id":434260,"date":"2022-07-11T19:55:44","date_gmt":"2022-07-12T00:55:44","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=434260"},"modified":"2022-07-11T19:55:46","modified_gmt":"2022-07-12T00:55:46","slug":"piden-a-alumnos-de-nuevo-ingreso-de-la-upn-presentarse-en-la-universidad","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/11\/piden-a-alumnos-de-nuevo-ingreso-de-la-upn-presentarse-en-la-universidad\/","title":{"rendered":"Piden a alumnos de nuevo ingreso de la UPN presentarse en la universidad"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">43<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2022%2F07%2F11%2Fpiden-a-alumnos-de-nuevo-ingreso-de-la-upn-presentarse-en-la-universidad%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/11\/piden-a-alumnos-de-nuevo-ingreso-de-la-upn-presentarse-en-la-universidad\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Francisco Rosas\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo.-<\/strong> Directivos de la Universidad Pedag\u00f3gica Nacional (UPN), sede Huejutla, informan de manera urgente a los alumnos de nuevo ingreso y de reinscripci\u00f3n que &#8220;la inscripci\u00f3n no se realizar\u00e1 en plataforma&#8221;, por lo que deber\u00e1n presentarse en la universidad para solicitar su referencia bancaria el d\u00eda 11 y 12 de julio del a\u00f1o en curso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El horario en que se estar\u00e1 atendiendo a los estudiantes, ser\u00e1 de 11 de la ma\u00f1ana a 5 de la tarde, por lo que se les pide llevar la documentaci\u00f3n que subieron a la plataforma en original y copia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se dio a conocer a los alumnos de nuevo ingreso y a los alumnos de reinscripci\u00f3n de las Licenciaturas en Intervenci\u00f3n Educativa, Educaci\u00f3n e Innovaci\u00f3n Pedag\u00f3gica y Maestr\u00eda en Educaci\u00f3n Campo Pr\u00e1ctica, que las inscripciones se realizar\u00e1n del 8 al 15 de julio de 2022, por lo que es importante contar con la referencia bancaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Francisco Rosas\/Zunoticia Huejutla, Hgo.- Directivos de la Universidad Pedag\u00f3gica Nacional (UPN), sede Huejutla, informan de manera urgente a los alumnos de nuevo ingreso y de reinscripci\u00f3n que &#8220;la inscripci\u00f3n no se realizar\u00e1 en plataforma&#8221;, por lo que deber\u00e1n presentarse en la universidad para solicitar su referencia bancaria el d\u00eda 11 y 12 de julio&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2022\/07\/11\/piden-a-alumnos-de-nuevo-ingreso-de-la-upn-presentarse-en-la-universidad\/\">Seguir leyendo <span class=\"screen-reader-text\">Piden a alumnos de nuevo ingreso de la UPN presentarse en la universidad<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":434241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-434260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/434260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=434260"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/434260\/revisions"}],"predecessor-version":[{"id":434261,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/434260\/revisions\/434261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/434241"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=434260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=434260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=434260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}