{"id":506176,"date":"2023-09-28T23:27:00","date_gmt":"2023-09-29T05:27:00","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=506176"},"modified":"2023-09-29T00:11:56","modified_gmt":"2023-09-29T06:11:56","slug":"espejeando-por-perseo-772","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2023\/09\/28\/espejeando-por-perseo-772\/","title":{"rendered":"ESPEJEANDO por Perseo"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">39<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2023%2F09%2F28%2Fespejeando-por-perseo-772%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2023\/09\/28\/espejeando-por-perseo-772\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\">\u2022 AYER FUE la visita de Claudia Sheinbaum y su mensaje inicial fue recordar el tema de cuando fue estudiante, del reconocimiento a los estudiantes que pidi\u00f3 cuando hay demandas e inconformidad no hab\u00eda dudas que los estudiantes tienen la raz\u00f3n, teniendo la m\u00e1xima casa de estudios un reclamo en la UAEH, pues el mensaje se tom\u00f3 como viene y para quien lo quiera entender, a\u00fan cuando no lo personaliz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Claudia Sheinbaum Pardo trae su recorrido por el pa\u00eds con la firma de los acuerdos por la unidad por la Cuarta Transformaci\u00f3n; su llegada a Pachuca, el coraz\u00f3n de Hidalgo, fue un primer mensaje de que no dejar\u00e1 pasar nada ni a nadie y su vocero Gerardo Fern\u00e1ndez Noro\u00f1a trae la consigna frontal para decirle a sus adversarios del Frente por M\u00e9xico del PRI, PAN y PRD lo que considera sus verdades por la historia reciente del pa\u00eds de un r\u00e9gimen validado en el Pacto por M\u00e9xico que los habr\u00eda consolidado como una alternancia de intereses de grupo del poder econ\u00f3mico y pol\u00edtico del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Claudia Sheinbaum habl\u00f3 de la responsabilidad de todos y todas para seguir construyendo un pa\u00eds fuerte, destac\u00f3 el superpeso, las obras del tren interoce\u00e1nico y del proyecto del Tren Maya y de dar continuidad a los programas del gobierno para el fortalecimiento nacional de los de abajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Se refiri\u00f3 a los cambios profundos no solo en el poder ejecutivo, del legislativo y propuesto esos cambios al poder judicial, pues dijo los m\u00e1s pobres tambi\u00e9n requieren justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 La lectura es clara, la ruta trazada de Andr\u00e9s Manuel L\u00f3pez Obrador es la propuesta de continuidad y es ah\u00ed el tema de hablar de la responsabilidad social, si quiere el pueblo la transformaci\u00f3n o quiere regresar con los grupos privilegiados, los del pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 El lleno del lugar permite ver la estrategia del Movimiento de Regeneraci\u00f3n Nacional en cada estado y su posicionamiento pol\u00edtico tiene en firme la visi\u00f3n nacionalista del Presidente de M\u00e9xico Andr\u00e9s Manuel L\u00f3pez Obrador, el sello de garant\u00eda que le da a Claudia la seguridad que las estructuras nacionales que a lo largo de cinco a\u00f1os se han consolidado de manera paulatina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Claudia Sheinbaum lleg\u00f3 a Hidalgo pisando fuerte, es a simple vista una primera visita que permite ver con claridad el nivel de contexto nacional que veremos y los mensajes est\u00e1n ah\u00ed en cada Instituto pol\u00edtico de Hidalgo que representa la Cuarta Transformaci\u00f3n, Morena y sus aliados en Hidalgo llevan la suma de Nueva Alianza y los maestros en Hidalgo son y con mucho, una fuerza mayor que el Partido del Trabajo y del Partido Verde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 DE LA HUASTECA muchos ilusos subieron al evento buscando dejarse ver, lo que deben saber es que ser\u00e1n puestas a prueba sus convicciones pol\u00edticas, pues el proyecto de naci\u00f3n est\u00e1 por encima de los intereses pol\u00edticos personales y de grupo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Se trata de que fue bien clara la propuesta, s\u00f3lo hay una ruta de Transformaci\u00f3n y esta la tiene Morena, por eso se entiende que muchos son los llamados pero solo unos cuantos ser\u00e1n los considerados a los espacios pol\u00edticos en juego, el resto tendr\u00e1 que esperar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 EL FRENTE por M\u00e9xico del PRI, PAN y PRD tienen enfrente una aplanadora y las descalificaciones y se\u00f1alamientos en redes sociales se incrementaron pues las herramientas de comunicaci\u00f3n moderna son parte de las tareas para hacer campa\u00f1a por aire, saben que le han apostado a una mujer hidalguense como X\u00f3chitl G\u00e1lvez, pero tendr\u00e1n que ser m\u00e1s que las propuestas&nbsp; como logren convencer al electorado de una sociedad despierta, con sus sentidos alertas&nbsp; y emociones muy utilizadas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2023\/09\/Imagen-de-WhatsApp-2023-09-28-a-las-23.16.07_7d7e8091-1024x682.jpg\" alt=\"\" class=\"wp-image-506169\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2023\/09\/Imagen-de-WhatsApp-2023-09-28-a-las-23.16.07_7d7e8091-1024x682.jpg 1024w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2023\/09\/Imagen-de-WhatsApp-2023-09-28-a-las-23.16.07_7d7e8091-300x200.jpg 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2023\/09\/Imagen-de-WhatsApp-2023-09-28-a-las-23.16.07_7d7e8091-768x512.jpg 768w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2023\/09\/Imagen-de-WhatsApp-2023-09-28-a-las-23.16.07_7d7e8091.jpg 1079w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 AYER FUE la visita de Claudia Sheinbaum y su mensaje inicial fue recordar el tema de cuando fue estudiante, del reconocimiento a los estudiantes que pidi\u00f3 cuando hay demandas e inconformidad no hab\u00eda dudas que los estudiantes tienen la raz\u00f3n, teniendo la m\u00e1xima casa de estudios un reclamo en la UAEH, pues el mensaje&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2023\/09\/28\/espejeando-por-perseo-772\/\">Seguir leyendo <span class=\"screen-reader-text\">ESPEJEANDO por Perseo<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":506170,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[176],"tags":[205],"class_list":["post-506176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espejeando","tag-espejeando","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/506176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=506176"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/506176\/revisions"}],"predecessor-version":[{"id":506178,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/506176\/revisions\/506178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/506170"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=506176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=506176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=506176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}