{"id":517819,"date":"2023-12-12T17:09:35","date_gmt":"2023-12-12T23:09:35","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=517819"},"modified":"2023-12-12T17:09:36","modified_gmt":"2023-12-12T23:09:36","slug":"mc-abierto-a-todos-los-liderazgos-politicos-max-rivera","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2023\/12\/12\/mc-abierto-a-todos-los-liderazgos-politicos-max-rivera\/","title":{"rendered":"MC abierto a todos los liderazgos pol\u00edticos: Max Rivera"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"float:left\"><div class=\"counts mashsbcount\">38<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2023%2F12%2F12%2Fmc-abierto-a-todos-los-liderazgos-politicos-max-rivera%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2023\/12\/12\/mc-abierto-a-todos-los-liderazgos-politicos-max-rivera\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p><em>Por \u00c1ngel Silverio\/Zunoticia<\/em><\/p>\n\n\n\n<p><strong>San Felipe Orizatl\u00e1n, Hgo.<\/strong>&#8211; De cara al proceso electoral del pr\u00f3ximo a\u00f1o, los distintos partidos est\u00e1n analizando perfiles de posibles candidatos a los diferentes puestos de elecci\u00f3n popular, por lo que el Partido Movimiento Ciudadano no es la excepci\u00f3n, se revisa a quienes pudieran abanderar las f\u00f3rmulas, seg\u00fan dio a conocer el representante local de Movimiento Ciudadano, Max Rivera, quien agreg\u00f3 que, el partido est\u00e1 abierto a todos aquellos que gusten sumarse.<br>Entrevistado al respecto, sobre el trabajo que ha venido realizando el partido en este municipio, respondi\u00f3, &#8211; \u201cVamos caminando, se va consolidando el proyecto de Movimiento Ciudadano, esperamos que pronto llegue la ola naranja a San Felipe y como digo, vamos recorriendo las comunidades para hablarles del proyecto que se viene del 2024\u201d.<br>Dijo que, el partido ha venido creciendo a nivel nacional, &#8211; \u201cConvirti\u00e9ndose en una fuerza importante, en Hidalgo no es la excepci\u00f3n, pero tambi\u00e9n en los 84 municipios hay presencia, hoy vemos que hay partido en la sierra y la huasteca y en el municipio vemos una consolidaci\u00f3n del movimiento naranja\u201d.<br>Cuestionado si no ser\u00e1n una recicladora de todos aquellos que no se vean beneficiados en sus partidos, precis\u00f3, &#8211; \u201cTenemos perfiles con caras conocidas, perfiles nuevos, MC le apuesta a las caras nuevas, a los comerciantes a los empresarios, gente que a veces no ha participado en pol\u00edtica o ajena a esto, hoy el partido les hace la invitaci\u00f3n y esos son los perfiles id\u00f3neos que habremos de llevar a la pr\u00f3xima contienda electoral\u201d<br>Sin embargo, recalc\u00f3 que, no se pueden cerrar a sumar liderazgos natos de otros partidos, -\u201cLo ha comentado la dirigencia, son bienvenidos todos, los panistas, priistas, morenistas que a veces no encuentran la oportunidad de participar en esos partidos, tienen las puertas abiertas en MC, no digo que seremos una recicladora, seremos selectos, analistas de esos perfiles para que pudieran en un momento encabezar alguna f\u00f3rmula en este 2024\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por \u00c1ngel Silverio\/Zunoticia San Felipe Orizatl\u00e1n, Hgo.&#8211; De cara al proceso electoral del pr\u00f3ximo a\u00f1o, los distintos partidos est\u00e1n analizando perfiles de posibles candidatos a los diferentes puestos de elecci\u00f3n popular, por lo que el Partido Movimiento Ciudadano no es la excepci\u00f3n, se revisa a quienes pudieran abanderar las f\u00f3rmulas, seg\u00fan dio a conocer el&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2023\/12\/12\/mc-abierto-a-todos-los-liderazgos-politicos-max-rivera\/\">Seguir leyendo <span class=\"screen-reader-text\">MC abierto a todos los liderazgos pol\u00edticos: Max Rivera<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":517820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[179,180],"tags":[229,129],"class_list":["post-517819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huasteca","category-orizatlan","tag-huasteca","tag-orizatlan","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/517819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=517819"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/517819\/revisions"}],"predecessor-version":[{"id":517821,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/517819\/revisions\/517821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/517820"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=517819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=517819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=517819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}