{"id":517892,"date":"2023-12-12T19:55:18","date_gmt":"2023-12-13T01:55:18","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=517892"},"modified":"2023-12-12T19:55:19","modified_gmt":"2023-12-13T01:55:19","slug":"abogado-al-cereso-por-presunto-fraude","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2023\/12\/12\/abogado-al-cereso-por-presunto-fraude\/","title":{"rendered":"Abogado al CERESO por presunto fraude"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"float:left\"><div class=\"counts mashsbcount\">57<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2023%2F12%2F12%2Fabogado-al-cereso-por-presunto-fraude%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2023\/12\/12\/abogado-al-cereso-por-presunto-fraude\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<ul class=\"wp-block-list\">\n<li>Fue aprehendido por elementos de la Divisi\u00f3n de Investigaci\u00f3n de la Agencia de Investigaci\u00f3n Criminal del grupo Huejutla.<\/li>\n<\/ul>\n\n\n\n<p><em>Por Francisco Rosas\/Zunoticia<\/em><\/p>\n\n\n\n<p><strong>Huejutla, Hgo.-<\/strong> Elementos de la Divisi\u00f3n de Investigaci\u00f3n de la Agencia de Investigaci\u00f3n Criminal del grupo Huejutla, cumplieron una orden de aprehensi\u00f3n en contra de conocido abogado se\u00f1alado como probable responsable del delito de fraude.<\/p>\n\n\n\n<p>El profesionista investigado de iniciales F. O. S., con domicilio en la colonia El Carmen de esta ciudad, fue asegurada la tarde de este martes 12 de diciembre, en la gasolinera Fayad, ubicada en el bulevar central de la carretera M\u00e9xico \u2013 Tampico y a este individuo se le relaciona en la causa penal 13\/2023.<\/p>\n\n\n\n<p>De acuerdo con el expediente, el imputado presuntamente vendi\u00f3 cinco terrenos que no eran de su propiedad en la colonia Charco Azul de esta ciudad, por la cantidad de 150 mil pesos cada uno y la persona agraviada le pag\u00f3 la cantidad de 606 mil pesos, para adquirir la propiedad.<\/p>\n\n\n\n<p>Sin embargo, la afectada de iniciales A. E. M., descubri\u00f3 que los terrenos ten\u00edan otro due\u00f1o, motivo por el cual present\u00f3 su denuncia en la agencia del Ministerio P\u00fablico del Fuero Com\u00fan de este distrito judicial, por el delito de fraude y de esta manera el caso fue judicializado en el Juzgado Penal de La Lima, Jaltoc\u00e1n.<\/p>\n\n\n\n<p>Por el delito en el que incurri\u00f3 F. O. S., un poco despu\u00e9s de las 14:30 horas fue ingresado al Centro de Reinserci\u00f3n Social (CERESO), donde qued\u00f3 a disposici\u00f3n del Juez de Control y este mi\u00e9rcoles ser\u00e1 la audiencia inicial para la imputaci\u00f3n&nbsp;del&nbsp;delito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Francisco Rosas\/Zunoticia Huejutla, Hgo.- Elementos de la Divisi\u00f3n de Investigaci\u00f3n de la Agencia de Investigaci\u00f3n Criminal del grupo Huejutla, cumplieron una orden de aprehensi\u00f3n en contra de conocido abogado se\u00f1alado como probable responsable del delito de fraude. El profesionista investigado de iniciales F. O. S., con domicilio en la colonia El Carmen de esta&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2023\/12\/12\/abogado-al-cereso-por-presunto-fraude\/\">Seguir leyendo <span class=\"screen-reader-text\">Abogado al CERESO por presunto fraude<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":517896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[178],"tags":[259],"class_list":["post-517892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiaca","tag-policiaca","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/517892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=517892"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/517892\/revisions"}],"predecessor-version":[{"id":517899,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/517892\/revisions\/517899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/517896"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=517892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=517892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=517892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}