{"id":519834,"date":"2023-12-27T17:35:17","date_gmt":"2023-12-27T23:35:17","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=519834"},"modified":"2023-12-27T17:36:43","modified_gmt":"2023-12-27T23:36:43","slug":"modulo-del-ine-atendio-a-ciudadanos","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2023\/12\/27\/modulo-del-ine-atendio-a-ciudadanos\/","title":{"rendered":"M\u00f3dulo del INE atendi\u00f3 a ciudadanos"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"float:left\"><div class=\"counts mashsbcount\">0<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2023%2F12%2F27%2Fmodulo-del-ine-atendio-a-ciudadanos%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2023\/12\/27\/modulo-del-ine-atendio-a-ciudadanos\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p><em>Por Le\u00f3n Eduardo Fern\u00e1ndez Huesca \/ Zunoticia<\/em><\/p>\n\n\n\n<p><strong>Xochiatipan, Hgo<\/strong>. &#8211; De las 09:00 a las 14:00 horas de este mi\u00e9rcoles, el m\u00f3dulo itinerante del Instituto Nacional Electoral atendi\u00f3 a ciudadanos xochiatipenses, quienes acudieron a la invitaci\u00f3n hecha a trav\u00e9s del gobierno local que preside \u00d3scar Bautista Guti\u00e9rrez.<\/p>\n\n\n\n<p>No obstante, el periodo vacacional que tienen las instituciones gubernamentales, personal del citado instituto acudi\u00f3 formalmente a cumplir con su compromiso de brindar sus servicios a quienes necesitaban hacer cambios de domicilio o corregir sus datos en la credencial para votar con fotograf\u00eda.<\/p>\n\n\n\n<p>De acuerdo con la informaci\u00f3n proporcionada, se atendieron a m\u00e1s de 40 personas procedentes de comunidades y barrios del municipio, los cuales constataron el inter\u00e9s que existe por parte del \u00f3rgano electoral para que sea mayor el n\u00famero de personas las que participen en el proceso para renovar los poderes ejecutivo y legislativo federal, as\u00ed como los ayuntamientos y Congreso local en Hidalgo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Le\u00f3n Eduardo Fern\u00e1ndez Huesca \/ Zunoticia Xochiatipan, Hgo. &#8211; De las 09:00 a las 14:00 horas de este mi\u00e9rcoles, el m\u00f3dulo itinerante del Instituto Nacional Electoral atendi\u00f3 a ciudadanos xochiatipenses, quienes acudieron a la invitaci\u00f3n hecha a trav\u00e9s del gobierno local que preside \u00d3scar Bautista Guti\u00e9rrez. No obstante, el periodo vacacional que tienen las&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2023\/12\/27\/modulo-del-ine-atendio-a-ciudadanos\/\">Seguir leyendo <span class=\"screen-reader-text\">M\u00f3dulo del INE atendi\u00f3 a ciudadanos<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":519835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[179,202],"tags":[229,135],"class_list":["post-519834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huasteca","category-xochiatipan","tag-huasteca","tag-xochiatipan","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/519834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=519834"}],"version-history":[{"count":2,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/519834\/revisions"}],"predecessor-version":[{"id":519837,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/519834\/revisions\/519837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/519835"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=519834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=519834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=519834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}