{"id":531915,"date":"2024-03-18T22:23:37","date_gmt":"2024-03-19T04:23:37","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=531915"},"modified":"2024-03-18T22:54:22","modified_gmt":"2024-03-19T04:54:22","slug":"oficial-confirman-a-san-roman-por-morena","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/18\/oficial-confirman-a-san-roman-por-morena\/","title":{"rendered":"Oficial, confirman a San Rom\u00e1n, por Morena"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">33<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F03%2F18%2Foficial-confirman-a-san-roman-por-morena%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/18\/oficial-confirman-a-san-roman-por-morena\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<ul class=\"wp-block-list\">\n<li>Connotados personajes ser\u00e1n candidatos en Sierra y Huasteca.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Por Mois\u00e9s Medrano\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo.-<\/strong> La Comisi\u00f3n Nacional de Elecciones de Morena dio a conocer los nombres y apellidos de los propuestos a las alcald\u00edas que revela con cada uno de los hombres y mujeres con los que habr\u00e1n de enfrentar el escenario electoral 2024.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"250\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/eZy-Watermark_18-03-2024_08-15-10-1820p.m.jpg\" alt=\"\" class=\"wp-image-531896\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">En los municipios huastecos y serranos destacables personalidades tendr\u00e1n la oportunidad de jugar su escenario pol\u00edtico local y la tarea es el de respaldar los proyectos institucionales del Movimiento de Regeneraci\u00f3n Nacional.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"604\" height=\"914\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/eZy-Watermark_18-03-2024_08-16-56-6810p.m.jpg\" alt=\"\" class=\"wp-image-531895\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Jos\u00e9 Alfredo San Rom\u00e1n Duval es el candidato y propuesta para competir por Huejutla, el controvertido ex alcalde de Guillermo Amador lo es por Jaltoc\u00e1n, en Tlanchinol la ex regidora Nora Aidh\u00e9 Luciano Mart\u00ednez con sensibilidad y car\u00e1cter del movimiento de las bases de Morena y proyecto viable con sumas importante con la sociedad y actores pol\u00edticos; Marco Andrade en San Felipe Orizatl\u00e1n es un joven de impulso e imagen fresca, Gabriela Naranjo Bautista en Atlapexco es una propuesta social viable y competitiva, Francisca Lara Vel\u00e1zquez en Yahualica con trayectoria hist\u00f3rica en el Movimiento de Regeneraci\u00f3n Nacional e identidad con las bases guindas; Antonio Gonz\u00e1lez Valent\u00edn en Huautla es un hombre mayor con un historial transparente, en Xochiatipan Mar\u00eda Luisa Hern\u00e1ndez Le\u00f3n otra mujer de trayecto de las bases de Morena, Jessica Cortez Baltazar en Huazalingo es la imagen fresca, es de profesi\u00f3n abogada; en Tepehuac\u00e1n Francisco Mart\u00ednez Enr\u00edquez un proyecto que ya demostr\u00f3 de que est\u00e1 hecho y representa la esperanza de un municipio que ha sido gobernado por una sola familia.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"381\" height=\"284\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/eZy-Watermark_18-03-2024_08-16-31-9510p.m.jpg\" alt=\"\" class=\"wp-image-531894\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e1 en breve el registro y presentaci\u00f3n formal de los abanderados en cuyo proyecto encabeza Morena.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"859\" height=\"1121\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/eZy-Watermark_18-03-2024_08-15-32-1470p.m.jpg\" alt=\"\" class=\"wp-image-531892\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Nueva Alianza presenta en sesi\u00f3n las propuestas en los municipios que encabezan como Calnali y parte de la Sierra Alta en la que podr\u00e1n&nbsp;competir.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"952\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/eZy-Watermark_18-03-2024_08-16-06-9030p.m.jpg\" alt=\"\" class=\"wp-image-531891\"\/><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/eZy-Watermark_18-03-2024_08-15-48-4850p.m.jpg\" alt=\"\" class=\"wp-image-531890\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"975\" height=\"650\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/eZy-Watermark_18-03-2024_08-00-24-6690p.m-1.jpg\" alt=\"\" class=\"wp-image-531906\"\/><\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"1312\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/eZy-Watermark_18-03-2024_09-20-35-3940p.m.jpg\" alt=\"\" class=\"wp-image-531924\"\/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Por Mois\u00e9s Medrano\/Zunoticia Huejutla, Hgo.- La Comisi\u00f3n Nacional de Elecciones de Morena dio a conocer los nombres y apellidos de los propuestos a las alcald\u00edas que revela con cada uno de los hombres y mujeres con los que habr\u00e1n de enfrentar el escenario electoral 2024. En los municipios huastecos y serranos destacables personalidades tendr\u00e1n la&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/18\/oficial-confirman-a-san-roman-por-morena\/\">Seguir leyendo <span class=\"screen-reader-text\">Oficial, confirman a San Rom\u00e1n, por Morena<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":531893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-531915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/531915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=531915"}],"version-history":[{"count":2,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/531915\/revisions"}],"predecessor-version":[{"id":531925,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/531915\/revisions\/531925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/531893"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=531915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=531915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=531915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}