{"id":532227,"date":"2024-03-21T11:48:30","date_gmt":"2024-03-21T17:48:30","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=532227"},"modified":"2024-03-21T11:48:33","modified_gmt":"2024-03-21T17:48:33","slug":"tlanchinol-conmemoro-el-natalicio-de-benito-juarez","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/21\/tlanchinol-conmemoro-el-natalicio-de-benito-juarez\/","title":{"rendered":"Tlanchinol conmemor\u00f3 el natalicio de Benito Ju\u00e1rez"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">2<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F03%2F21%2Ftlanchinol-conmemoro-el-natalicio-de-benito-juarez%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/21\/tlanchinol-conmemoro-el-natalicio-de-benito-juarez\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Mois\u00e9s Medrano\/Redacci\u00f3n<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tlanchinol, Hgo.- <\/strong>Este jueves, en la Plaza Bicentenario, se llevaron a cabo los honores a la bandera mexicana en conmemoraci\u00f3n al natalicio del Benem\u00e9rito de las Am\u00e9ricas, \u201cBenito Ju\u00e1rez Garc\u00eda\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En dicho acto c\u00edvico estuvieron presentes personal en general de la presidencia municipal, as\u00ed como directores, maestros y alumnos de las instituciones educativas de la cabecera municipal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al t\u00e9rmino del evento c\u00edvico se realiz\u00f3 la colocaci\u00f3n de la ofrenda floral y guardia de honor al busto de \u201cBenito Ju\u00e1rez Garc\u00eda\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ex presidente Benito Ju\u00e1rez Garc\u00eda naci\u00f3 el 21 de marzo de 1806, en San Pablo Guelatao, Oaxaca. Tuvo una ni\u00f1ez precaria y durante a\u00f1os estudi\u00f3 por s\u00ed mismo, hasta que lleg\u00f3 a la ciudad de Oaxaca, donde ingres\u00f3 al seminario; ah\u00ed concluy\u00f3 estudios de Lat\u00edn, Filosof\u00eda y Teolog\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno de Tlanchinol 2020-2024 agradeci\u00f3 a todas las instituciones educativas por su participaci\u00f3n y apoyo para llevar a cabo este importante acto c\u00edvico.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"933\" height=\"524\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/Zunoticia-Huejutla-1-156.png\" alt=\"\" class=\"wp-image-532229\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por Mois\u00e9s Medrano\/Redacci\u00f3n Tlanchinol, Hgo.- Este jueves, en la Plaza Bicentenario, se llevaron a cabo los honores a la bandera mexicana en conmemoraci\u00f3n al natalicio del Benem\u00e9rito de las Am\u00e9ricas, \u201cBenito Ju\u00e1rez Garc\u00eda\u201d. En dicho acto c\u00edvico estuvieron presentes personal en general de la presidencia municipal, as\u00ed como directores, maestros y alumnos de las instituciones&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/21\/tlanchinol-conmemoro-el-natalicio-de-benito-juarez\/\">Seguir leyendo <span class=\"screen-reader-text\">Tlanchinol conmemor\u00f3 el natalicio de Benito Ju\u00e1rez<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":532228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[219,201],"tags":[346,127],"class_list":["post-532227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sierra","category-tlanchinol","tag-sierra","tag-tlanchinol","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/532227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=532227"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/532227\/revisions"}],"predecessor-version":[{"id":532230,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/532227\/revisions\/532230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/532228"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=532227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=532227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=532227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}