{"id":532231,"date":"2024-03-21T12:03:11","date_gmt":"2024-03-21T18:03:11","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=532231"},"modified":"2024-03-21T12:03:14","modified_gmt":"2024-03-21T18:03:14","slug":"realizan-desfile-y-festival-de-primavera-2024","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/21\/realizan-desfile-y-festival-de-primavera-2024\/","title":{"rendered":"Realizan desfile y festival de Primavera 2024"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">11<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F03%2F21%2Frealizan-desfile-y-festival-de-primavera-2024%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/21\/realizan-desfile-y-festival-de-primavera-2024\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Gabriela Hern\u00e1ndez\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>San Felipe Orizatl\u00e1n, Hgo<\/strong>.- La ma\u00f1ana de este jueves 21 de marzo, en punto de las 9:30 a.m. dio inici\u00f3 el desfile de primavera con la participaci\u00f3n de los diferentes jardines de ni\u00f1os del municipio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El desfile comenz\u00f3 en la calle Hidalgo, a la altura del CAIC, recorriendo las principales calles de la zona centro para culminar en las inmediaciones del Casino Orizatlense, posteriormente se tuvo la participaci\u00f3n de los peque\u00f1os con diferentes n\u00fameros art\u00edsticos, danzas y bailables representativos a la primavera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los jardines de ni\u00f1os que se dieron cita fueron: \u201cGriselda Lara Vargas\u201d, el CAIC, \u201cProfesor Roberto Cer\u00f3n S\u00e1nchez\u201d, \u201cDr. Nicasio Castillo S\u00e1nchez\u201d, \u201cReyno Rivera Fern\u00e1ndez\u201d, \u201cValle verde\u201d y \u201cLeona Vicario\u201d, teniendo la participaci\u00f3n de 420 ni\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre aplausos y risas se vivi\u00f3 el festival de primavera, contando con la presencia de los padres de familia y autoridades municipales.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"933\" height=\"524\" data-id=\"532234\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/Zunoticia-Huejutla-2-46.png\" alt=\"\" class=\"wp-image-532234\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"933\" height=\"524\" data-id=\"532233\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/Zunoticia-Huejutla-1-157.png\" alt=\"\" class=\"wp-image-532233\"\/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por Gabriela Hern\u00e1ndez\/Zunoticia San Felipe Orizatl\u00e1n, Hgo.- La ma\u00f1ana de este jueves 21 de marzo, en punto de las 9:30 a.m. dio inici\u00f3 el desfile de primavera con la participaci\u00f3n de los diferentes jardines de ni\u00f1os del municipio. El desfile comenz\u00f3 en la calle Hidalgo, a la altura del CAIC, recorriendo las principales calles de&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/21\/realizan-desfile-y-festival-de-primavera-2024\/\">Seguir leyendo <span class=\"screen-reader-text\">Realizan desfile y festival de Primavera 2024<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":532232,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[179,180],"tags":[229,129],"class_list":["post-532231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huasteca","category-orizatlan","tag-huasteca","tag-orizatlan","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/532231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=532231"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/532231\/revisions"}],"predecessor-version":[{"id":532235,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/532231\/revisions\/532235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/532232"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=532231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=532231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=532231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}