{"id":533013,"date":"2024-03-26T18:53:09","date_gmt":"2024-03-27T00:53:09","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=533013"},"modified":"2024-03-26T18:53:12","modified_gmt":"2024-03-27T00:53:12","slug":"mediante-denuncia-anonima-rescatan-a-victimas-de-secuestro","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/26\/mediante-denuncia-anonima-rescatan-a-victimas-de-secuestro\/","title":{"rendered":"Mediante denuncia an\u00f3nima, rescatan a v\u00edctimas de secuestro"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">44<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F03%2F26%2Fmediante-denuncia-anonima-rescatan-a-victimas-de-secuestro%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/26\/mediante-denuncia-anonima-rescatan-a-victimas-de-secuestro\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pachuca de Soto, Hgo.-<\/strong> Elementos adscritos a la Secretar\u00eda de Seguridad P\u00fablica de Hidalgo llevaron a cabo la liberaci\u00f3n de un hombre y una mujer, quienes presuntamente hab\u00edan sido privados de la libertad, y en la acci\u00f3n fueron detenidas cuatro personas por su probable relaci\u00f3n con los hechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue mediante una llamada an\u00f3nima, que los agentes recibieron el reporte sobre un domicilio de la colonia Nacozari, municipio de Tizayuca, en el cual se escuchaban gritos de auxilio de al menos dos personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De inmediato se realiz\u00f3 el despliegue operativo hasta el lugar, donde los oficiales establecieron seguridad perimetral, adem\u00e1s de contactar al propietario de la vivienda, la cual se encontraba alquilada, para posteriormente solicitar el acceso a dicho inmueble.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al ingresar en el domicilio, fueron hallados y puestos a salvo una pareja de j\u00f3venes, quienes refirieron haber sido privados ilegalmente de su libertad, adem\u00e1s de que sus familiares estaban siendo presionados para pagar por su rescate.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De manera simult\u00e1nea fueron detenidos en el sitio tres hombres y una mujer, identificados como E. G. H., A. G. I. P., B. J.P. T. y M. J. P. G., quienes fueron se\u00f1alados por las v\u00edctimas como sus captores y de haber provocado lesiones en uno de los j\u00f3venes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, las personas detenidas fueron trasladas a la Unidad Especializada de Combate al Secuestro, de la Procuradur\u00eda General de Justicia de Hidalgo, donde se determinar\u00e1 su situaci\u00f3n jur\u00eddica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La SSPH reitera el llamado a la ciudadan\u00eda para contribuir con estas acciones, a trav\u00e9s de reportes mediante el 911 de Emergencia y\/o 089 de Denuncia An\u00f3nima.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"933\" height=\"524\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/Zunoticia-Huejutla-381.png\" alt=\"\" class=\"wp-image-533015\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Pachuca de Soto, Hgo.- Elementos adscritos a la Secretar\u00eda de Seguridad P\u00fablica de Hidalgo llevaron a cabo la liberaci\u00f3n de un hombre y una mujer, quienes presuntamente hab\u00edan sido privados de la libertad, y en la acci\u00f3n fueron detenidas cuatro personas por su probable relaci\u00f3n con los hechos. Fue mediante una llamada an\u00f3nima,&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/26\/mediante-denuncia-anonima-rescatan-a-victimas-de-secuestro\/\">Seguir leyendo <span class=\"screen-reader-text\">Mediante denuncia an\u00f3nima, rescatan a v\u00edctimas de secuestro<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":533014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-533013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/533013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=533013"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/533013\/revisions"}],"predecessor-version":[{"id":533016,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/533013\/revisions\/533016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/533014"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=533013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=533013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=533013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}