{"id":533026,"date":"2024-03-26T19:08:51","date_gmt":"2024-03-27T01:08:51","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=533026"},"modified":"2024-03-26T19:08:54","modified_gmt":"2024-03-27T01:08:54","slug":"lo-hallaron-ahorcado-7","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/26\/lo-hallaron-ahorcado-7\/","title":{"rendered":"\u00a1Lo hallaron ahorcado!"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">40<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F03%2F26%2Flo-hallaron-ahorcado-7%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/26\/lo-hallaron-ahorcado-7\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Francisco Rosas\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Atlapexco, Hgo.-<\/strong> Atado del cuello con una cuerda, encuentran ahorcado a habitante de la localidad de Tecacahuaco, perteneciente a este municipio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hoy occiso de nombre Orlando N., de 30 a\u00f1os, lo hallaron colgado de un barrote de madera de un ba\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cuerpo sin vida del masculino fue localizado el pasado lunes 25 de marzo y de acuerdo con el reporte de las autoridades polic\u00edacas, el hombre presuntamente se suicid\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al lugar de los hechos arribaron elementos de Seguridad P\u00fablica, Agentes de la Divisi\u00f3n de Investigaci\u00f3n y personal de la Procuradur\u00eda General de Justicia del Estado de Hidalgo (PGJEH), para realizar las diligencias de ley, as\u00ed como ordenar el levantamiento del cad\u00e1ver.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Francisco Rosas\/Zunoticia Atlapexco, Hgo.- Atado del cuello con una cuerda, encuentran ahorcado a habitante de la localidad de Tecacahuaco, perteneciente a este municipio. El hoy occiso de nombre Orlando N., de 30 a\u00f1os, lo hallaron colgado de un barrote de madera de un ba\u00f1o. El cuerpo sin vida del masculino fue localizado el pasado&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/26\/lo-hallaron-ahorcado-7\/\">Seguir leyendo <span class=\"screen-reader-text\">\u00a1Lo hallaron ahorcado!<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":533027,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[182,179],"tags":[133,229],"class_list":["post-533026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atlapexco","category-huasteca","tag-atlapexco","tag-huasteca","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/533026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=533026"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/533026\/revisions"}],"predecessor-version":[{"id":533028,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/533026\/revisions\/533028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/533027"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=533026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=533026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=533026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}