{"id":533072,"date":"2024-03-26T22:44:44","date_gmt":"2024-03-27T04:44:44","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=533072"},"modified":"2024-03-26T22:44:48","modified_gmt":"2024-03-27T04:44:48","slug":"llegan-a-huejutla-boletas-electorales-en-mayo","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/26\/llegan-a-huejutla-boletas-electorales-en-mayo\/","title":{"rendered":"Llegan a Huejutla boletas electorales en mayo"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">60<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F03%2F26%2Fllegan-a-huejutla-boletas-electorales-en-mayo%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/26\/llegan-a-huejutla-boletas-electorales-en-mayo\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<ul class=\"wp-block-list\">\n<li>Recibe INE Hidalgo 14 toneladas de material electoral<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pachuca, Hgo.-<\/strong> El Instituto Nacional Electoral (INE) en el estado de Hidalgo, recibi\u00f3 en las juntas distritales ejecutivas, m\u00e1s de 14 toneladas de material y documentaci\u00f3n electoral sin emblemas de los partidos para el Proceso Electoral Concurrente 2023 \u2013 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El material recibido consta de urnas, mamparas, paquetes electorales, aviso de localizaci\u00f3n de casilla, bolsas para entrega de material a las mesas directivas, etiquetas de recuento para cada tipo de elecci\u00f3n, sobres para expedientes, cintas de seguridad y materiales de escritorio como cojines para sellos, tinta, lapiceros, tijeras, entre otros art\u00edculos de papeler\u00eda que son necesarios para el buen funcionamiento de las casillas a instalarse el pr\u00f3ximo 2 de junio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Vocal de Organizaci\u00f3n Electoral del INE Hidalgo, Licda. Claudia Santos Ordo\u00f1ez, inform\u00f3 que los materiales y documentaci\u00f3n electoral ser\u00e1n resguardados en las bodegas de los Consejos Distritales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, el INE en Hidalgo inform\u00f3 que el 9 de mayo pr\u00f3ximo, arribar\u00e1n a la 01 Junta Distrital Ejecutiva en Huejutla de Reyes, las boletas electorales, l\u00edquido indeleble y documentaci\u00f3n con emblemas de partidos pol\u00edticos y el 15 del mismo mes, al resto de las seis juntas distritales electorales mediante un dispositivo de custodia por las fuerzas armadas debido a que la salvaguarda y cuidado de las mismas son considerados como un asunto de seguridad nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Pachuca, Hgo.- El Instituto Nacional Electoral (INE) en el estado de Hidalgo, recibi\u00f3 en las juntas distritales ejecutivas, m\u00e1s de 14 toneladas de material y documentaci\u00f3n electoral sin emblemas de los partidos para el Proceso Electoral Concurrente 2023 \u2013 2024. El material recibido consta de urnas, mamparas, paquetes electorales, aviso de localizaci\u00f3n de&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/26\/llegan-a-huejutla-boletas-electorales-en-mayo\/\">Seguir leyendo <span class=\"screen-reader-text\">Llegan a Huejutla boletas electorales en mayo<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":533073,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-533072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/533072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=533072"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/533072\/revisions"}],"predecessor-version":[{"id":533074,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/533072\/revisions\/533074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/533073"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=533072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=533072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=533072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}