{"id":533372,"date":"2024-03-28T18:59:51","date_gmt":"2024-03-29T00:59:51","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=533372"},"modified":"2024-03-28T18:59:54","modified_gmt":"2024-03-29T00:59:54","slug":"desmantela-ssph-punto-de-narcomenudeo-en-mixquiahuala","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/28\/desmantela-ssph-punto-de-narcomenudeo-en-mixquiahuala\/","title":{"rendered":"Desmantela SSPH punto de narcomenudeo en Mixquiahuala"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">25<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F03%2F28%2Fdesmantela-ssph-punto-de-narcomenudeo-en-mixquiahuala%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/28\/desmantela-ssph-punto-de-narcomenudeo-en-mixquiahuala\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pachuca de Soto, Hgo.-<\/strong> Un total de siete personas y m\u00e1s de 3 mil dosis de presunta droga, fueron asegurados por elementos de la Secretar\u00eda de Seguridad P\u00fablica de Hidalgo (SSPH) durante un despliegue operativo en el municipio de Mixquiahuala.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de la Unidad de Inteligencia del Centro de Control, Comando, Comunicaciones, C\u00f3mputo, Coordinaci\u00f3n e Inteligencia (C5i), se iniciaron las investigaciones respecto a un establecimiento, ubicado en la avenida Hidalgo de la colonia centro, el cual hab\u00eda sido se\u00f1alado como supuesto punto de venta y distribuci\u00f3n de narc\u00f3ticos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resultado de las indagatorias, las autoridades en llevaron a cabo la orden de cateo en el negocio denominado \u201cNexus\u201d en el que se hallaron 300 dosis de hierba seca con caracter\u00edsticas de la marihuana, 140 dosis de posible droga sint\u00e9tica \u201ccristal\u201d, as\u00ed como equipo tecnol\u00f3gico.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este mismo punto fueron detenidas dos mujeres y un hombre quienes, al observar el arribo de los agentes policiales al establecimiento, intentaron huir a bordo de dos motocicletas, siendo intervenidos dentro del primer c\u00edrculo de seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la revisi\u00f3n a las personas identificados como C. G. S., Y. C. H. y L.G. M., les fueron decomisadas 2 mil 500 dosis de presunta marihuana, 267 dosis de droga sint\u00e9tica \u201ccristal\u201d, 24 dosis de droga tipo \u201cpiedra\u201d, 20 dosis de probable coca\u00edna, adem\u00e1s de 13 pipas de cristal.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, derivado de los filtros de revisi\u00f3n y vigilancia, se procedi\u00f3 a la intervenci\u00f3n de una camioneta Jeep, color gris, tripulada por 4 sujetos que responden a las siglas de J. L. G. C., L. M. P. J., K. P. C. y R. G. M. M., quienes ten\u00edan en posesi\u00f3n 130 dosis de droga sint\u00e9tica \u201ccristal\u201d, 50 mil pesos en efectivo y se presume, son integrantes de \u201cLos Solas\u201d, grupo delictivo que opera en la regi\u00f3n Tula.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez finalizados los procedimientos judiciales, los detenidos, veh\u00edculos y objetos asegurados, fueron puestos a disposici\u00f3n del agente del Ministerio P\u00fablico correspondiente, quien determinar\u00e1 su situaci\u00f3n jur\u00eddica. En tanto, se contin\u00faan las investigaciones que deriven de los hechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se reitera el llamado a la ciudadan\u00eda para contribuir con estas acciones, realizando reportes mediante el 911 de Emergencias y\/o al 089 de Denuncia An\u00f3nima.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"933\" height=\"524\" data-id=\"533376\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/Zunoticia-Huejutla-3-23.png\" alt=\"\" class=\"wp-image-533376\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"933\" height=\"524\" data-id=\"533374\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/Zunoticia-Huejutla-2-77.png\" alt=\"\" class=\"wp-image-533374\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"933\" height=\"524\" data-id=\"533375\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/03\/Zunoticia-Huejutla-446.png\" alt=\"\" class=\"wp-image-533375\"\/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Pachuca de Soto, Hgo.- Un total de siete personas y m\u00e1s de 3 mil dosis de presunta droga, fueron asegurados por elementos de la Secretar\u00eda de Seguridad P\u00fablica de Hidalgo (SSPH) durante un despliegue operativo en el municipio de Mixquiahuala.&nbsp; A trav\u00e9s de la Unidad de Inteligencia del Centro de Control, Comando, Comunicaciones,&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/03\/28\/desmantela-ssph-punto-de-narcomenudeo-en-mixquiahuala\/\">Seguir leyendo <span class=\"screen-reader-text\">Desmantela SSPH punto de narcomenudeo en Mixquiahuala<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":533373,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-533372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/533372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=533372"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/533372\/revisions"}],"predecessor-version":[{"id":533377,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/533372\/revisions\/533377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/533373"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=533372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=533372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=533372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}