{"id":534234,"date":"2024-04-04T20:24:05","date_gmt":"2024-04-05T02:24:05","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=534234"},"modified":"2024-04-04T20:24:08","modified_gmt":"2024-04-05T02:24:08","slug":"personal-de-visitaduria-de-la-pgjeh-atendio-quejas-contra-funcionarios","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/04\/personal-de-visitaduria-de-la-pgjeh-atendio-quejas-contra-funcionarios\/","title":{"rendered":"Personal de Visitadur\u00eda de la PGJEH atendi\u00f3 quejas contra funcionarios"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">4<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F04%2F04%2Fpersonal-de-visitaduria-de-la-pgjeh-atendio-quejas-contra-funcionarios%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/04\/personal-de-visitaduria-de-la-pgjeh-atendio-quejas-contra-funcionarios\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Francisco Rosas\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo.-<\/strong> Este jueves 4 de abril personal de la Visitadur\u00eda de la Procuradur\u00eda General de Justicia del Estado de Hidalgo (PGJEH) inspeccion\u00f3 la agencia del Ministerio P\u00fablico del Fuero Com\u00fan de este distrito judicial y atendi\u00f3 quejas ciudadanas contra funcionarios de esta dependencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su llegada a las oficinas, los inspectores realizaron una revisi\u00f3n de manera aleatoria a las carpetas de investigaci\u00f3n, con la finalidad de corroborar que su integraci\u00f3n se lleve a cabo sin irregularidades y verificar el correcto desempe\u00f1o de las y los servidores p\u00fablicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los supervisores inspeccionaron el funcionamiento de la dependencia de procuraci\u00f3n de justicia, adem\u00e1s atendieron quejas y denuncias de la poblaci\u00f3n y anunciaron que tambi\u00e9n ser\u00e1n recibidas a trav\u00e9s de la l\u00ednea de PROCURATEL 800 912 1314, en contra de Ministerios P\u00fablicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, trascendi\u00f3 que, la supervisi\u00f3n ser\u00e1 continua y en caso de detectarse alguna irregularidad o una ineficiencia la indicaci\u00f3n del Procurador es dar inicio a un procedimiento de responsabilidad para sancionar en concordancia con la gravedad de la falta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos de los quejosos que pidieron omitir sus nombres por temor a represalias, manifestaron que, las visitas deben de ser constantes, porque hay mucho rezago y sobre todo nepotismo por parte de algunos agentes del Ministerio P\u00fablico de la Unidad de Investigaci\u00f3n y Litigaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, exhortan al personal de la Visitadur\u00eda para que tambi\u00e9n vengan en d\u00edas que no sean de periodo vacacional y atiendan las quejas de la ciudadan\u00eda, ya que la gente de escasos recursos no puede acudir hasta la PGJEH de la ciudad&nbsp;de&nbsp;Pachuca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Francisco Rosas\/Zunoticia Huejutla, Hgo.- Este jueves 4 de abril personal de la Visitadur\u00eda de la Procuradur\u00eda General de Justicia del Estado de Hidalgo (PGJEH) inspeccion\u00f3 la agencia del Ministerio P\u00fablico del Fuero Com\u00fan de este distrito judicial y atendi\u00f3 quejas ciudadanas contra funcionarios de esta dependencia. A su llegada a las oficinas, los inspectores&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/04\/personal-de-visitaduria-de-la-pgjeh-atendio-quejas-contra-funcionarios\/\">Seguir leyendo <span class=\"screen-reader-text\">Personal de Visitadur\u00eda de la PGJEH atendi\u00f3 quejas contra funcionarios<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":534243,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[178],"tags":[259],"class_list":["post-534234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiaca","tag-policiaca","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/534234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=534234"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/534234\/revisions"}],"predecessor-version":[{"id":534244,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/534234\/revisions\/534244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/534243"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=534234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=534234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=534234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}