{"id":535297,"date":"2024-04-12T12:02:49","date_gmt":"2024-04-12T18:02:49","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=535297"},"modified":"2024-04-12T12:02:53","modified_gmt":"2024-04-12T18:02:53","slug":"se-pronostica-que-el-frente-frio-numero-45-ocasione-chubascos-con-lluvias-puntuales-fuertes-en-la-peninsula-de-yucatan","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/12\/se-pronostica-que-el-frente-frio-numero-45-ocasione-chubascos-con-lluvias-puntuales-fuertes-en-la-peninsula-de-yucatan\/","title":{"rendered":"Se pronostica que el frente fr\u00edo n\u00famero 45 ocasione chubascos con lluvias puntuales fuertes en la Pen\u00ednsula de Yucat\u00e1n"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">42<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F04%2F12%2Fse-pronostica-que-el-frente-frio-numero-45-ocasione-chubascos-con-lluvias-puntuales-fuertes-en-la-peninsula-de-yucatan%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/12\/se-pronostica-que-el-frente-frio-numero-45-ocasione-chubascos-con-lluvias-puntuales-fuertes-en-la-peninsula-de-yucatan\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<ul class=\"wp-block-list\">\n<li>Se prev\u00e9n rachas fuertes de viento en el noroeste, norte y noreste de M\u00e9xico.<br><br>&nbsp;<\/li>\n\n\n\n<li>Continuar\u00e1 el ambiente de caluroso a muy caluroso sobre gran parte del territorio nacional.<br><br>&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy se pronostica que el frente fr\u00edo n\u00famero 45 se extienda frente a las costas de Quintana Roo y, en interacci\u00f3n con un canal de baja presi\u00f3n sobre la Pen\u00ednsula de Yucat\u00e1n, ocasione lluvias puntuales fuertes (de 25 a 50 mm) en dicha entidad; as\u00ed como chubascos (de 5 a 25 mm) en Campeche y lluvias aisladas (de 0.1 a 5 mm) en zonas de Yucat\u00e1n. Durante la tarde, el frente mencionado se desplazar\u00e1 sobre el Mar Caribe, dejando de afectar al territorio mexicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, el ingreso de aire h\u00famedo procedente del Oc\u00e9ano Pac\u00edfico y Golfo de M\u00e9xico en combinaci\u00f3n con un canal de baja presi\u00f3n sobre la Mesa Central, generar\u00e1n lluvias aisladas en el Estado de M\u00e9xico, Ciudad de M\u00e9xico, Guerrero, Hidalgo, Michoac\u00e1n, Oaxaca, Puebla, Tabasco y Veracruz. Cabe mencionar que las precipitaciones pronosticadas para este d\u00eda podr\u00edan estar acompa\u00f1adas de descargas el\u00e9ctricas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La masa de aire fr\u00edo asociada a dicho frente producir\u00e1 viento de componente norte, con rachas de 60 a 80 kil\u00f3metros por hora (km\/h) en el Istmo de Tehuantepec; as\u00ed como rachas de 40 a 60 km\/h en Campeche, Quintana Roo, Tabasco y Yucat\u00e1n, con oleaje de 2 a 3 metros (m) de altura en el Golfo de Tehuantepec.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adicionalmente, se espera viento con rachas de 50 a 70 km\/h en el Golfo de California y con tolvaneras en Baja California, Chihuahua, Coahuila, Durango, Nuevo Le\u00f3n, San Luis Potos\u00ed, Sonora, Tamaulipas y Zacatecas; adem\u00e1s de rachas de 40 a 60 km\/h y posibles tolvaneras en Aguascalientes, Ciudad de M\u00e9xico, Estado de M\u00e9xico, Guanajuato, Hidalgo, Jalisco, Morelos, Nayarit, Puebla, Quer\u00e9taro, Sinaloa y Tlaxcala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se prev\u00e9 que los vientos fuertes pronosticados podr\u00edan originar el derribo de \u00e1rboles y anuncios publicitarios, por lo que se exhorta a la poblaci\u00f3n atender los avisos del Servicio Meteorol\u00f3gico Nacional (SMN), de la Comisi\u00f3n Nacional del Agua (Conagua) y seguir las recomendaciones de las autoridades estatales y de Protecci\u00f3n Civil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, una circulaci\u00f3n anticicl\u00f3nica en niveles medios de la atm\u00f3sfera originar\u00e1 una baja probabilidad de lluvia, as\u00ed como ambiente de caluroso a muy caluroso sobre gran parte del territorio nacional, con temperaturas m\u00e1ximas superiores a 45 grados Celsius en Guerrero y Michoac\u00e1n; de 40 a 45 grados en Colima, Jalisco, Morelos, Nayarit y Sinaloa; as\u00ed como de 35 a 40 grados en Baja California, Campeche, Chiapas, el suroeste del Estado de M\u00e9xico, Sonora, Nuevo Le\u00f3n, Oaxaca, el suroeste de Puebla, Quintana Roo, San Luis Potos\u00ed, Tabasco, Tamaulipas, Veracruz, Yucat\u00e1n y Zacatecas, y de 30 a 35 grados en Aguascalientes, Baja California Sur, Chihuahua, Coahuila, el occidente de Durango, Guanajuato, Hidalgo y Quer\u00e9taro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a las temperaturas mencionadas, se recomienda a la poblaci\u00f3n tomar medidas preventivas como evitar la exposici\u00f3n prolongada a la radiaci\u00f3n solar, hidratarse adecuadamente, poner especial atenci\u00f3n a enfermos cr\u00f3nicos, ni\u00f1os y adultos mayores, as\u00ed como atender las indicaciones del sector Salud y de Protecci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Civil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a las temperaturas m\u00ednimas, se prev\u00e9n estimados de -5 a 0 grados Celsius con heladas en sierras de Chihuahua, Coahuila, Durango, Nuevo Le\u00f3n y Zacatecas, y de 0 a 5 grados en sierras de Aguascalientes, Baja California, Estado de M\u00e9xico, Guanajuato, Hidalgo, Jalisco, Michoac\u00e1n, Oaxaca, Puebla, Quer\u00e9taro, San Luis Potos\u00ed, Sonora, el suroeste de Tamaulipas, Tlaxcala y Veracruz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por las bajas temperaturas pronosticadas, se recomienda a la poblaci\u00f3n tomar medidas preventivas, como abrigarse e hidratarse adecuadamente, evitar cambios bruscos de temperatura, poner especial atenci\u00f3n a enfermos cr\u00f3nicos, ni\u00f1os y adultos mayores. Asimismo, las temperaturas g\u00e9lidas podr\u00edan provocar el congelamiento de la carpeta asf\u00e1ltica, por lo que se exhorta a la poblaci\u00f3n atender los avisos del Servicio Meteorol\u00f3gico Nacional (SMN) y seguir las recomendaciones de las autoridades estatales y de Protecci\u00f3n Civil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy se pronostica que el frente fr\u00edo n\u00famero 45 se extienda frente a las costas de Quintana Roo y, en interacci\u00f3n con un canal de baja presi\u00f3n sobre la Pen\u00ednsula de Yucat\u00e1n, ocasione lluvias puntuales fuertes (de 25 a 50 mm) en dicha entidad; as\u00ed como chubascos (de 5 a 25 mm) en Campeche y&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/12\/se-pronostica-que-el-frente-frio-numero-45-ocasione-chubascos-con-lluvias-puntuales-fuertes-en-la-peninsula-de-yucatan\/\">Seguir leyendo <span class=\"screen-reader-text\">Se pronostica que el frente fr\u00edo n\u00famero 45 ocasione chubascos con lluvias puntuales fuertes en la Pen\u00ednsula de Yucat\u00e1n<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":535298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[218],"tags":[],"class_list":["post-535297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=535297"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535297\/revisions"}],"predecessor-version":[{"id":535299,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535297\/revisions\/535299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/535298"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=535297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=535297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=535297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}