{"id":535406,"date":"2024-04-12T19:15:07","date_gmt":"2024-04-13T01:15:07","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=535406"},"modified":"2024-04-12T19:15:12","modified_gmt":"2024-04-13T01:15:12","slug":"ssph-captura-a-banda-dedicada-al-robo-de-transporte-de-carga-en-tepeji","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/12\/ssph-captura-a-banda-dedicada-al-robo-de-transporte-de-carga-en-tepeji\/","title":{"rendered":"SSPH captura a banda dedicada al robo de\u00a0transporte de carga en Tepeji"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">24<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F04%2F12%2Fssph-captura-a-banda-dedicada-al-robo-de-transporte-de-carga-en-tepeji%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/12\/ssph-captura-a-banda-dedicada-al-robo-de-transporte-de-carga-en-tepeji\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pachuca de Soto, Hgo.-<\/strong> En seguimiento a labores de investigaci\u00f3n e inteligencia operativa, la Secretar\u00eda de Seguridad P\u00fablica de Hidalgo logr\u00f3 la captura de cinco hombres y una mujer, quienes son miembros de &#8220;Los R\u00e1banos&#8221;, grupo generador de violencia en el municipio de Tepeji del R\u00edo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la ejecuci\u00f3n de cuatro cateos simult\u00e1neos en domicilios de la colonia Santiago Tlautla, fueron detenidos J. F. R. B., alias \u201cEl Panchito\u201d, E. P. R., S. G. C., M. R. A., B. M. R. I. y T. J. M., quienes est\u00e1n supuestamente relacionados con actividades de narcomenudeo y robo a transporte de carga en la regi\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante las diligencias desarrolladas de manera conjunta con la Procuradur\u00eda General de Justicia del Estado de Hidalgo (PGJEH) y Sedena, se aseguraron dos armas largas, 21 cartuchos \u00fatiles de diferentes calibres, tres cargadores para arma larga, equipo de telefon\u00eda celular y de radiocomunicaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, les fueron incautadas 906 dosis de hierba seca con caracter\u00edsticas propias de la marihuana, 190 dosis de droga sint\u00e9tica y una camioneta marca Jeep, color blanco, supuestamente vinculada a robos efectuados sobre la autopista M\u00e9xico-Quer\u00e9taro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez finalizados los procedimientos judiciales, los detenidos y objetos asegurados fueron puestos a disposici\u00f3n del agente del Ministerio P\u00fablico correspondiente, quien determinar\u00e1 su situaci\u00f3n jur\u00eddica. Mientras tanto, contin\u00faan las investigaciones derivadas de los hechos.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"933\" height=\"524\" data-id=\"535409\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/04\/Zunoticia-Huejutla-2-52.png\" alt=\"\" class=\"wp-image-535409\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"933\" height=\"524\" data-id=\"535408\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/04\/Zunoticia-Huejutla-1-127.png\" alt=\"\" class=\"wp-image-535408\"\/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Pachuca de Soto, Hgo.- En seguimiento a labores de investigaci\u00f3n e inteligencia operativa, la Secretar\u00eda de Seguridad P\u00fablica de Hidalgo logr\u00f3 la captura de cinco hombres y una mujer, quienes son miembros de &#8220;Los R\u00e1banos&#8221;, grupo generador de violencia en el municipio de Tepeji del R\u00edo.&nbsp; Tras la ejecuci\u00f3n de cuatro cateos simult\u00e1neos&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/12\/ssph-captura-a-banda-dedicada-al-robo-de-transporte-de-carga-en-tepeji\/\">Seguir leyendo <span class=\"screen-reader-text\">SSPH captura a banda dedicada al robo de\u00a0transporte de carga en Tepeji<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":535407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-535406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=535406"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535406\/revisions"}],"predecessor-version":[{"id":535410,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535406\/revisions\/535410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/535407"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=535406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=535406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=535406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}