{"id":535415,"date":"2024-04-12T19:40:23","date_gmt":"2024-04-13T01:40:23","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=535415"},"modified":"2024-04-12T19:40:27","modified_gmt":"2024-04-13T01:40:27","slug":"capacitacion-en-lengua-de-senas-mexicana","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/12\/capacitacion-en-lengua-de-senas-mexicana\/","title":{"rendered":"Capacitaci\u00f3n en Lengua de Se\u00f1as Mexicana"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">38<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F04%2F12%2Fcapacitacion-en-lengua-de-senas-mexicana%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/12\/capacitacion-en-lengua-de-senas-mexicana\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pachuca de Soto, Hgo.-<\/strong> La capacitaci\u00f3n en Lengua de Se\u00f1as Mexicana (LSM) dirigida a servidoras p\u00fablicas culmin\u00f3 este viernes, luego de que integrantes de la agrupaci\u00f3n de apoyo tur\u00edstico y vial, \u00c1ngeles Verdes, recibieran sus constancias de nivel b\u00e1sico dos, por parte de la Secretar\u00eda de Bienestar e Inclusi\u00f3n Social (Sebiso).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta actividad tuvo como objetivo coadyuvar a la comunicaci\u00f3n efectiva con personas no oyentes que utilizan la LSM, ampliando as\u00ed el campo de acci\u00f3n del personal que tiene contacto con la poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tuvo una duraci\u00f3n de tres meses, y al t\u00e9rmino de la misma, las participantes pudieron generar una conversaci\u00f3n, con la que dieron indicaciones de distancia y tiempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la etapa tres de este curso, se pretende integrar dos grupos m\u00e1s, ya que se realizar\u00e1n conversaciones frente a frente, de tal forma que se pueda llevar a la pr\u00e1ctica los saberes adquiridos durante las capacitaciones previas de los dos primeros niveles, as\u00ed como fortalecer las habilidades de gram\u00e1tica y gesticulaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Pachuca de Soto, Hgo.- La capacitaci\u00f3n en Lengua de Se\u00f1as Mexicana (LSM) dirigida a servidoras p\u00fablicas culmin\u00f3 este viernes, luego de que integrantes de la agrupaci\u00f3n de apoyo tur\u00edstico y vial, \u00c1ngeles Verdes, recibieran sus constancias de nivel b\u00e1sico dos, por parte de la Secretar\u00eda de Bienestar e Inclusi\u00f3n Social (Sebiso). Esta actividad&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/12\/capacitacion-en-lengua-de-senas-mexicana\/\">Seguir leyendo <span class=\"screen-reader-text\">Capacitaci\u00f3n en Lengua de Se\u00f1as Mexicana<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":535417,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-535415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=535415"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535415\/revisions"}],"predecessor-version":[{"id":535418,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535415\/revisions\/535418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/535417"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=535415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=535415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=535415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}