{"id":535705,"date":"2024-04-15T14:55:53","date_gmt":"2024-04-15T20:55:53","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=535705"},"modified":"2024-04-15T14:55:57","modified_gmt":"2024-04-15T20:55:57","slug":"retransmiten-debate-presidencial-en-ceresos-de-hidalgo","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/15\/retransmiten-debate-presidencial-en-ceresos-de-hidalgo\/","title":{"rendered":"Retransmiten debate presidencial en Ceresos de Hidalgo"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">34<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F04%2F15%2Fretransmiten-debate-presidencial-en-ceresos-de-hidalgo%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/15\/retransmiten-debate-presidencial-en-ceresos-de-hidalgo\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pachuca de Soto, Hgo<\/strong>.- La Secretar\u00eda de Seguridad P\u00fablica de Hidalgo (SSPH), a trav\u00e9s de la Subsecretar\u00eda de Reinserci\u00f3n Social, retransmiti\u00f3, en los Centros de Reinserci\u00f3n Social de la entidad, el debate entre quienes ostentan las candidaturas a la Presidencia de la Rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior, con el objetivo de dar la oportunidad de sufragar, de forma informada, a las personas que se encuentran en prisi\u00f3n preventiva, es decir, que no tienen a\u00fan una sentencia y que est\u00e1n en posibilidades de votar en las elecciones del 2 de junio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta iniciativa surgi\u00f3 de la resoluci\u00f3n del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n (TEPJF), qui\u00e9n determin\u00f3 que las personas sin sentencia condenatoria y bajo prisi\u00f3n preventiva conservan sus derechos pol\u00edtico-electorales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, Hidalgo cuenta con 12 centros penitenciarios ubicados en Actopan, Apan, Huichapan, Huejutla, Ixmiquilpan, Jacala, Mixquiahuala, Molango, Pachuca, Tenango de Doria, Tula y Tulancingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto que, hasta el corte de abril 2024, la SSPH report\u00f3 un total de 810 personas que esperan una sentencia, de las cuales 753 son hombres y 57 son mujeres; no obstante, dichas cifras podr\u00e1n variar debido a los cambios en la situaci\u00f3n jur\u00eddica de cada persona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, el Instituto Nacional Electoral (INE) llevar\u00e1 a cabo la votaci\u00f3n anticipada correspondiente al Proceso Electoral Concurrente 2023-2024, del 6 al 20 de mayo, en atenci\u00f3n al principio de presunci\u00f3n de inocencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para que las personas en prisi\u00f3n puedan votar, deber\u00e1n tener la credencial de elector vigente y los datos biom\u00e9tricos (huellas digitales) con una calidad que permita identificarlas con certeza.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"933\" height=\"524\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/04\/Zunoticia-Huejutla-2-56.png\" alt=\"\" class=\"wp-image-535707\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Pachuca de Soto, Hgo.- La Secretar\u00eda de Seguridad P\u00fablica de Hidalgo (SSPH), a trav\u00e9s de la Subsecretar\u00eda de Reinserci\u00f3n Social, retransmiti\u00f3, en los Centros de Reinserci\u00f3n Social de la entidad, el debate entre quienes ostentan las candidaturas a la Presidencia de la Rep\u00fablica. Lo anterior, con el objetivo de dar la oportunidad de&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/15\/retransmiten-debate-presidencial-en-ceresos-de-hidalgo\/\">Seguir leyendo <span class=\"screen-reader-text\">Retransmiten debate presidencial en Ceresos de Hidalgo<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":535706,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-535705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=535705"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535705\/revisions"}],"predecessor-version":[{"id":535708,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535705\/revisions\/535708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/535706"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=535705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=535705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=535705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}