{"id":535722,"date":"2024-04-15T16:40:56","date_gmt":"2024-04-15T22:40:56","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=535722"},"modified":"2024-04-15T16:41:00","modified_gmt":"2024-04-15T22:41:00","slug":"upt-y-upe-firmaron-convenio-de-colaboracion","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/15\/upt-y-upe-firmaron-convenio-de-colaboracion\/","title":{"rendered":"UPT y UPE firmaron convenio de colaboraci\u00f3n\u00a0"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">1<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F04%2F15%2Fupt-y-upe-firmaron-convenio-de-colaboracion%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/15\/upt-y-upe-firmaron-convenio-de-colaboracion\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pachuca de Soto, Hgo.-<\/strong> La Universidad Polit\u00e9cnica de Tulancingo (UPT) y la Universidad Polit\u00e9cnica de la Energ\u00eda (UPE) firmaron un convenio de colaboraci\u00f3n con la finalidad de reforzar actividades que coadyuven al incremento de las relaciones acad\u00e9micas, cient\u00edficas y culturales entre ambas casas de estudios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fortalecer la vinculaci\u00f3n entre la UPT y las instituciones educativas de nivel superior permite el intercambio acad\u00e9mico y la cooperaci\u00f3n universitaria, mencion\u00f3 el rector de esta casa de estudios.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante se\u00f1alar que la UPT facilita la transferencia de conocimientos y tecnolog\u00edas desarrolladas en el \u00e1mbito acad\u00e9mico hacia la sociedad y el sector productivo, lo cual posibilita que la investigaci\u00f3n impacte de manera real y contribuya al desarrollo econ\u00f3mico y social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se crean redes de colaboraci\u00f3n entre instituciones educativas, empresas locales y comunidades, con lo cual se promueve la innovaci\u00f3n y el emprendimiento en diferentes \u00e1reas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derivado de la cercan\u00eda y similitud con algunos de los programas educativos, y a ra\u00edz de este convenio, las universidades llevar\u00e1n a cabo proyectos de investigaci\u00f3n y desarrollo tecnol\u00f3gico de forma conjunta, lo cual facilitar\u00e1 el intercambio de estudiantes, profesores e investigadores.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rector de la UPE destac\u00f3 la importancia que tiene estrechar lazos de colaboraci\u00f3n y hermandad entre ambas instituciones, lo cual favorecer\u00e1 la formaci\u00f3n integral de los estudiantes, al brindarles la oportunidad de participar en proyectos de investigaci\u00f3n aplicada, pr\u00e1cticas profesionales y programas de emprendimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con lo anterior, se complementa la formaci\u00f3n acad\u00e9mica del alumnado con experiencias pr\u00e1cticas y en contacto con el mundo laboral.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"933\" height=\"524\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/04\/Zunoticia-Huejutla-2-57.png\" alt=\"\" class=\"wp-image-535724\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Pachuca de Soto, Hgo.- La Universidad Polit\u00e9cnica de Tulancingo (UPT) y la Universidad Polit\u00e9cnica de la Energ\u00eda (UPE) firmaron un convenio de colaboraci\u00f3n con la finalidad de reforzar actividades que coadyuven al incremento de las relaciones acad\u00e9micas, cient\u00edficas y culturales entre ambas casas de estudios. Fortalecer la vinculaci\u00f3n entre la UPT y las&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/15\/upt-y-upe-firmaron-convenio-de-colaboracion\/\">Seguir leyendo <span class=\"screen-reader-text\">UPT y UPE firmaron convenio de colaboraci\u00f3n\u00a0<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":535723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-535722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=535722"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535722\/revisions"}],"predecessor-version":[{"id":535725,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/535722\/revisions\/535725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/535723"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=535722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=535722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=535722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}